{"id":334,"date":"2024-05-25T07:40:28","date_gmt":"2024-05-25T05:40:28","guid":{"rendered":"https:\/\/www.phytomania.com\/plantes-medicinales\/?p=334"},"modified":"2025-11-12T15:25:31","modified_gmt":"2025-11-12T14:25:31","slug":"cannabis","status":"publish","type":"post","link":"https:\/\/www.phytomania.com\/plantes-medicinales\/cannabis\/","title":{"rendered":"CANNABIS"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.phytomania.com\/medicina-herbaria\/cannabis\/\"><img loading=\"lazy\" decoding=\"async\" width=\"32\" height=\"32\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/05\/Spain_flags_flag_8858.png\" alt=\"\" class=\"wp-image-42\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.phytomania.com\/herbal-medicine\/cannabis-hemp\/\"><img loading=\"lazy\" decoding=\"async\" width=\"32\" height=\"32\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/05\/EnglishLanguage_Flag1_26107.png\" alt=\"\" class=\"wp-image-44\"\/><\/a><\/figure>\n\n\n\n<p>C&rsquo;est une toute petite famille botanique qui comprend deux genres :<br>HUMULUS (le houblon) et CANNABIS (le chanvre), CANNABIS SATIVA=CANNABIS INDICA, CANNABACEAE.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"262\" height=\"380\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/05\/cannabis22comp.jpg\" alt=\"\" class=\"wp-image-335\" srcset=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/05\/cannabis22comp.jpg 262w, https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/05\/cannabis22comp-207x300.jpg 207w\" sizes=\"auto, (max-width: 262px) 100vw, 262px\" \/><\/figure>\n\n\n\n<p>Il existe une peu de confusion sur l&rsquo;existence ou non de plusieurs esp\u00e8ces de cannabis, qui sont d\u00e9crites parfois comme de simples sous-esp\u00e8ces ou vari\u00e9t\u00e9s de Cannabis sativa..<\/p>\n\n\n\n<p>Certains botanistes distinguent plusieurs \u00ab\u00a0types\u00a0\u00bb de chanvre :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cannabis sativa le chanvre cultiv\u00e9, esp\u00e8ce principale,<\/li>\n\n\n\n<li>Cannabis sativa &#8211; indica , le chanvre \u00ab\u00a0indien\u00a0\u00bb,<\/li>\n\n\n\n<li>Cannabis sativa- ruderalis, chanvre sauvage (Europe)<\/li>\n\n\n\n<li>Cannabis sativa- afghanica, chanvre afghan<\/li>\n<\/ul>\n\n\n\n<p>Depuis quelques ann\u00e9es, la culture du cannabis devenant possible l\u00e9galement dans certains pays europ\u00e9ens et nord-am\u00e9ricains, les \u00ab\u00a0cultivateurs de cannabis\u00a0\u00bb ont am\u00e9lior\u00e9s les vari\u00e9t\u00e9s culturales pour obtenir de meilleurs rendements et un pourcentage plus \u00e9lev\u00e9 en substances actives notamment en proc\u00e9dant \u00e0 des croisements, les esp\u00e8ces cultiv\u00e9es sont maintenant presque toutes des hybrides.<\/p>\n\n\n\n<p>Cannabis sativa ( l&rsquo;esp\u00e8ce type) est une plante qui fournit :<\/p>\n\n\n\n<p>une fibre v\u00e9g\u00e9tale utilis\u00e9e \u00e0 grande \u00e9chelle pendant tr\u00e8s longtemps pour faire les cordages les plus solides, des voiles pour la marine, des toiles ou des filets, l&rsquo;armature des tapis etc\u2026<br>une graine, le ch\u00e9nevis, riche en huile (32%) et en proteines (22%), utilis\u00e9e dans l&rsquo;\u00e9levage aviaire et accessoirement par les p\u00eacheurs \u00e0 la ligne,<br>des substances pharmacologiquement actives (cannabino\u00efdes) contenues dans les feuilles, les fleurs, la r\u00e9sine. en quantit\u00e9 et qualit\u00e9 variable.<\/p>\n\n\n\n<p>Cannabis sativa (probablement originaire d&rsquo;Asie) est cultiv\u00e9e ou r\u00e9colt\u00e9e depuis tr\u00e8s longtemps en Asie et en Europe.<\/p>\n\n\n\n<p>Les Chinois connaissent et utilisent le chanvre depuis plus de 4000 ans.<br>Les populations d&rsquo;Asie occidentale, Assyriens, Scythes puis Arabes appr\u00e9ciaient le pouvoir enivrant des vapeurs de r\u00e9sine de chanvre (brul\u00e9e comme encens).<br>C&rsquo;est lors de l&rsquo;expansion Islamique que d&rsquo;autres peuples du pourtour m\u00e9diterran\u00e9en l&rsquo;adopt\u00e8rent comme plante m\u00e9dicinale ou enivrante.<br>Son introduction en Europe remonte pour la France \u00e0 l&rsquo;exp\u00e9dition Napol\u00e9onienne d&rsquo;Egypte et fait suite \u00e0 la colonisation de l&rsquo;Inde par l&rsquo;Angleterre.<br>Quelques artistes europ\u00e9ens l&rsquo;ont un temps adopt\u00e9, le fameux club des haschishins 1840-1860 (Baudelaire et ses amis), mais au 19\u00e8me si\u00e8cle on s&rsquo;int\u00e9ressait surtout \u00e0 son usage m\u00e9dical.<br>Dans le nouveau monde, il fut d&rsquo;abord introduit au Mexique (marijuana) puis dans le sud des USA par les populations europ\u00e9ennes.<\/p>\n\n\n\n<p>Le chanvre \u00ab\u00a0indien\u00a0\u00bb est une plante annuelle, plus ou moins buissonnante et pouvant atteindre 5 m de haut ( en g\u00e9n\u00e9ral 1 \u00e0 2m ).<\/p>\n\n\n\n<p>Les feuilles ont une disposition et une forme diff\u00e9rentes selon le niveau sur la plante, pr\u00e8s de la base elles sont oppos\u00e9es et d\u00e9coup\u00e9es en 5 \u00e0 10 segments, pr\u00e8s des extr\u00e9mit\u00e9s elles sont alternes (en spirale) et peu d\u00e9coup\u00e9es (1 \u00e0 3 segments).<\/p>\n\n\n\n<p>Les plants m\u00e2les meurent apr\u00e8s l&rsquo;anth\u00e8se alors que les femelles vivent encore 1 \u00e0 2 mois apr\u00e8s la pollinisation.<\/p>\n\n\n\n<p>Les fleurs m\u00e2les sont group\u00e9es en panicules axiaux ou terminaux, les fleurs femelles sont en cymes compactes m\u00e9lang\u00e9es de bract\u00e9es foliac\u00e9es.<\/p>\n\n\n\n<p>CANNABIS CHANVRE INDIEN MARIJUANA HALLUCINOGENE ANTISPASMODIQUE ANTALGIQUE TRES REGLEMENTE<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"http:\/\/www.imagesud.com\"><img loading=\"lazy\" decoding=\"async\" width=\"336\" height=\"280\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesudbis.jpg\" alt=\"\" class=\"wp-image-1418\" srcset=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesudbis.jpg 336w, https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesudbis-300x250.jpg 300w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><\/a><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><a href=\"http:\/\/www.imagesud.com\">http:\/\/www.imagesud.com<\/a> site partenaire de phytomania.com<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">COMPOSITION CHIMIQUE ET PROPRIETES<\/h2>\n\n\n\n<p>De nombreux composants ont \u00e9t\u00e9 d\u00e9crits et isol\u00e9s du chanvre (huile essentielle, alcalo\u00efdes, flavono\u00efdes, sucres, acides gras..) mais les plus importants sont les CANNABINOIDES pr\u00e9sents dans les feuilles , les bract\u00e9es et surtout la r\u00e9sine exsud\u00e9e, mais ils sont absents des graines et des tiges.<\/p>\n\n\n\n<p>Parmi ces cannabino\u00efdes (il sont entre 60 et 90 selon les sp\u00e9cialistes), le plus important est le delta 9 tetrahydrocannabinol (THC).<br>C&rsquo;est une substance lipophile qui peut \u00eatre absorb\u00e9e par voie digestive ou respiratoire et qui, m\u00e9tabolis\u00e9e par le foie , donne de nombreux d\u00e9riv\u00e9s hydroxyl\u00e9s pharmacologiquement actifs et inactifs.<\/p>\n\n\n\n<p>Il semblerait que certains de ces d\u00e9riv\u00e9s soient plus actifs que le THC, ce qui explique en partie les effets plus rapides et plus marqu\u00e9s du cannabis chez les \u00ab\u00a0habitu\u00e9s\u00a0\u00bb au m\u00e9tabolisme h\u00e9patique d\u00e9j\u00e0 \u00ab\u00a0pr\u00eat\u00a0\u00bb.<\/p>\n\n\n\n<p>On retrouve du THC et ses d\u00e9riv\u00e9s dans les urines apr\u00e8s absorption, son \u00e9limination est lente .<br>Le THC et ses d\u00e9riv\u00e9s persistent dans le sang, et donc l&rsquo;urine, une \u00e0 plusieurs semaines apr\u00e8s la consommation de cannabis.<\/p>\n\n\n\n<p>Le THC (qui se fixe essentiellement sur les r\u00e9cepteurs endocannabinoides CB1) et ses d\u00e9riv\u00e9s m\u00e9tabolis\u00e9s dans l&rsquo;organisme interf\u00e8rent avec les NEURO-TRANSMETTEURS : s\u00e9rotonine, ac\u00e9tylcholine, acide gamma aminobutyrique, noradr\u00e9naline et provoquent des effets importants mais vari\u00e9s sur le psychisme, la perception sensorielle et le syst\u00e8me neuro-v\u00e9g\u00e9tatif en fonction de la dose ing\u00e9r\u00e9e et de la personnalit\u00e9 du sujet.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>sensation de bien \u00eatre avec l\u00e9g\u00e8re ivresse, d\u00e9tente et forte tendance au rire,<\/li>\n\n\n\n<li>ou au contraire l\u00e9g\u00e8re angoisse et anxi\u00e9t\u00e9,<\/li>\n\n\n\n<li>modification de la perception sensorielle ( les sons, les couleurs, la distance, les formes),<\/li>\n\n\n\n<li>modification de la perception temporelle (le temps est \u00e9lastique),<\/li>\n\n\n\n<li>perturbation de la coordination motrice (attention \u00e0 la conduite auto),<\/li>\n\n\n\n<li>alt\u00e9ration plus ou moins controlable de la m\u00e9moire avec association d&rsquo;id\u00e9es parfois confuses, parfois brillantes, souvent hors du propos en court,<\/li>\n\n\n\n<li>induction du sommeil, chez certains ce peut \u00eatre le seul effet,<\/li>\n\n\n\n<li>am\u00e9lioration ou modification des sensations sexuelles,<\/li>\n\n\n\n<li>\u00e0 forte dose, l&rsquo;anxi\u00e9t\u00e9 et l&rsquo;angoisse sont fr\u00e9quentes, les hallucinations plus marqu\u00e9es et durables, m\u00eame apr\u00e8s disparition du THC du sang.<\/li>\n<\/ul>\n\n\n\n<p>On consid\u00e8re que la toxicit\u00e9 du THC est faible, les toxicologues ne rel\u00e8vent pas d&rsquo;intoxication mortelle, par contre, le surdosage peut provoquer l&rsquo;apparition de psychoses aigues.<\/p>\n\n\n\n<p>Les \u00e9pid\u00e9miologistes mettent en garde contre l&rsquo;usage du cannabis chez les enfants et les jeunes adolescents car on observe chez eux, \u00e0 l&rsquo;\u00e2ge adulte, un pourcentage plus \u00e9lev\u00e9 que normal de psychoses graves.<\/p>\n\n\n\n<p>L&rsquo;accoutumance au THC est faible, la d\u00e9pendance physique \u00e9galement, l&rsquo;interruption de la prise de la drogue provoque un syndrome de sevrage surmontable sans m\u00e9dication majeure.<\/p>\n\n\n\n<p>Le cannabis et ses d\u00e9riv\u00e9s sont n\u00e9anmoins interdits de commerce et de consommation dans beaucoup de pays; la culture du chanvre est tr\u00e8s r\u00e8glement\u00e9e.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mais les LEGISLATIONS CHANGENT VITE A SON SUJET depuis la fin des ann\u00e9es 2000 .<\/h2>\n\n\n\n<p>Le THC a d&rsquo;autres propri\u00e9t\u00e9s pharmacologiques:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>c&rsquo;est un bronchodilatateur (asthme),<\/li>\n\n\n\n<li>il diminue la pression intra-oculaire (glaucome) ,<\/li>\n\n\n\n<li>il est antalgique (douleurs neuropathiques , cancer \u00e9volu\u00e9),<\/li>\n\n\n\n<li>il att\u00e9nue les troubles li\u00e9s \u00e0 la chimioth\u00e9rapie : vomissements, naus\u00e9es, perte d&rsquo;app\u00e9tit,<\/li>\n\n\n\n<li>ces effets sur les cancers et leurs m\u00e9tastases est \u00e9tudi\u00e9 mais controvers\u00e9<\/li>\n\n\n\n<li>il interagit peut-\u00eatre sur le m\u00e9tabolisme hormonal et modifie peut-\u00eatre la d\u00e9fense immunitaire, cela reste l&rsquo;objet de pol\u00e9miques.<\/li>\n<\/ul>\n\n\n\n<p>Deux autres cannabinoides int\u00e9ressent la communaut\u00e9 scientifique et les consommateurs de cannabis : le CANNABIDIOL ou CBD et le CANNABINOL ou CBN.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"http:\/\/www.imagesud.com\"><img loading=\"lazy\" decoding=\"async\" width=\"336\" height=\"280\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesud2bis.jpg\" alt=\"\" class=\"wp-image-1415\" srcset=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesud2bis.jpg 336w, https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesud2bis-300x250.jpg 300w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><\/a><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><a href=\"http:\/\/www.imagesud.com \">http:\/\/www.imagesud.com <\/a>site partenaire de phytomania.com<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">LE CANNABIDIOL<\/h2>\n\n\n\n<p>Le CBD poss\u00e8de moins d&rsquo;effet psychotrope mais interagit sur de nombreux r\u00e9cepteurs dans l&rsquo;organisme.<\/p>\n\n\n\n<p>Ces effets pharmacologiques globaux ne sont pas encore bien d\u00e9termin\u00e9s, citons en quelques uns:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Il agit sur la douleur, c&rsquo;est un antalgique (notamment les douleurs neuropathiques de la scl\u00e9rose en plaque),<\/li>\n\n\n\n<li>sur l&rsquo;excitabilit\u00e9 du syst\u00e8me nerveux central , c&rsquo;est un anticonvulsivant (convulsions, \u00e9pilepsie),<\/li>\n\n\n\n<li>il pourrait retarder la diss\u00e9mination de certaines cellules canc\u00e9reuses (m\u00e9tastases),<\/li>\n\n\n\n<li>il modifie l&rsquo;action du THC en retardant son \u00e9limination et en modulant l&rsquo;angoisse ou l&rsquo;anxi\u00e9t\u00e9 qui lui sont li\u00e9es,<\/li>\n\n\n\n<li>des \u00e9valuations sont en cours pour connaitre son effet sur des psychoses graves (schisophr\u00e9nie ).<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">LE CANNABINOL<\/h2>\n\n\n\n<p>Le CBN est un produit d&rsquo;oxydation du THC qui se forme pendant le s\u00e9chage du cannabis s&rsquo;il est trop prolong\u00e9, au soleil et \u00e0 l&rsquo;air libre.<br>Il n&rsquo;existe pas dans la plante fraiche mais peut dominer les effets du THC.<br>IL est s\u00e9datif du syst\u00e8me nerveux central ( tendance au sommeil, \u00e9tourdissement) parfois d\u00e9presion psychique, perte de motivation, indiff\u00e9rence, troubles de la m\u00e9moire chez ceux qui consomment beaucoup de cannabis en provenance d&rsquo;Am\u00e9rique du sud ou d&rsquo;Am\u00e9rique centrale.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">UTILISATIONS<\/h2>\n\n\n\n<p>Malgr\u00e9 l&rsquo;interdiction globale de son usage (mais les l\u00e9gislations des pays \u00e9voluent assez vite, et l&rsquo;utilisation \u00ab\u00a0r\u00e9cr\u00e9ative et m\u00e9dicale\u00a0\u00bb devient possible dans de nombreux pays : exemple Canada et de nombreux \u00e9tats am\u00e9ricains), le cannabis sativa est consomm\u00e9 un peu partout dans le monde pour l&rsquo;ivresse douce et les modifications sensorielles qu&rsquo;il induit sous forme de:<br><br>&#8211; cigarettes de feuilles pures ou m\u00e9lang\u00e9es avec du tabac,<br>&#8211; r\u00e9sine avec ou sans d\u00e9bris v\u00e9g\u00e9taux, fum\u00e9e ou ing\u00e9r\u00e9e,<br>&#8211; de formes tr\u00e8s concentr\u00e9es: essence ou extraits.<br><br>L&rsquo;usage purement m\u00e9dicinal est ancien (Chine, Inde, Europe), on s&rsquo;en servait comme antalgique, anti-convulsivant et soporifique : <br>&#8211; douleurs menstruelles,<br>&#8211; douleur de l&rsquo;accouchement, <br>&#8211; migraine, <br>&#8211; \u00ab\u00a0danse de St Guy\u00a0\u00bb, \u00e9pilepsie, <br>&#8211; pr\u00e9paration aux op\u00e9rations (Chine), <br>&#8211; pr\u00e9paration au combat (Arabes), <br>&#8211; aide \u00e0 la m\u00e9ditation (Inde). <br>&#8211; On le connaissait comme anti-asthmatique, calmant la toux.<br>&#8211; Il \u00e9tait utile aussi comme traitement d&rsquo;appoint dans le sevrage des opiac\u00e9s.<br>Cannabis sativa a fait partie pendant longtemps de la pharmacop\u00e9e britannique.<br><br>Actuellement, on reconna\u00eet son pouvoir anti-asthmatique par bronchodilatation et de nombreux d\u00e9riv\u00e9s du THC ont \u00e9t\u00e9 test\u00e9s pour leurs propri\u00e9t\u00e9s anti-convulsivantes, spasmolytiques ou analg\u00e9siques (calmant les douleurs), mais il existe souvent des effets secondaires importants sur le psychisme qui en limitent l&rsquo;utilisation.<br>De m\u00eame, on s&rsquo;est aper\u00e7u de son pouvoir anti\u00e9m\u00e9tique, surtout chez les patients en chimioth\u00e9rapie anticanc\u00e9reuse (observations chez des fumeurs r\u00e9guliers de marijuana); des d\u00e9riv\u00e9s ont \u00e9t\u00e9 test\u00e9s pour cette indication et paraissent prometteurs.<br><br>R\u00e9cemment le \u00ab SATIVEX \u00bb a \u00e9t\u00e9 autoris\u00e9 dans plusieurs pays occidentaux(dont l\u2019Espagne) . En France le sativex a \u00e9t\u00e9 autoris\u00e9 puis interdit , rien n&rsquo;est clair \u00e0 son sujet au niveau l\u00e9gal.<br>Ce m\u00e9dicament (a base de cannabidiol avec peu de THC) semble int\u00e9ressant pour calmer, entre autres, les douleurs tenaces de la sl\u00e9rose en plaques.<br>il s\u2019agit d\u2019un spray buccal, la p\u00e9n\u00e9tration du produit se faisant au niveau de la muqueuse de la bouche, le malade dosant lui-meme le nombre et la r\u00e9partition des pulv\u00e9risations dans la journ\u00e9e en fonction de ses \u00e9pisodes douloureux.<br>Les utilisateurs de cet extrait de cannabis notent l\u2019absence ou la mod\u00e9ration des effets \u00ab psychiques \u00bb.<br><br>D&rsquo;autres m\u00e9dicaments \u00e0 base de cannabino\u00efdes existent et sont commercialis\u00e9s dans certains pays europ\u00e9ens ou nord-am\u00e9ricains : exemples MARINOL = dronabinol (THC synth\u00e9tique), BEDROCAN, BEDIOL, BEDROBINOL, la l\u00e9gislation en France reste tr\u00e8s restrictive \u00e0 leur encontre.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Exp\u00e9rimentation dans l&rsquo;utilisation du cannabis m\u00e9dical en France en 2024<\/h2>\n\n\n\n<p>Depuis deux ans une exp\u00e9rimentation dans l\u2019utilisation du cannabis m\u00e9dical \u00e9tait organis\u00e9e en France de fa\u00e7on extr\u00eamement contr\u00f4l\u00e9e et pour des indications sp\u00e9cifiques, elle s\u2019est termin\u00e9e le 27 mars 2024.<\/p>\n\n\n\n<p>Les m\u00e9decins prescripteurs et les pharmaciens qui fournissaient les m\u00e9dicaments \u00e9taient form\u00e9s, et contr\u00f4l\u00e9s et devaient participer \u00e0 l\u2019\u00e9valuation de cet essai th\u00e9rapeutique qui a enrol\u00e9 3035 patients.<br>A la fin de cette exp\u00e9rience th\u00e9rapeutique il y avait encore 1842 patients qui continuaient \u00e0 \u00eatre trait\u00e9s et surveill\u00e9s.<\/p>\n\n\n\n<p>En fin d\u2019ann\u00e9e 2024 il est pr\u00e9vu que les autorit\u00e9s sanitaires fran\u00e7aises autorisent la prescription de m\u00e9dicaments \u00e0 base de cannabis de fa\u00e7on normale c\u2019est \u00e0 dire non exp\u00e9rimentale mais dans un cadre tr\u00e8s surveill\u00e9 car il s\u2019agit de m\u00e9dicaments de la cat\u00e9gorie des stup\u00e9fiants.<\/p>\n\n\n\n<p>Les 5 indications th\u00e9rapeutiques retenues par le comit\u00e9 scientifique pour exp\u00e9rimenter l\u2019usage de cannabis \u00e0 des fins m\u00e9dicales en 2021 \u00e9taient:<br>\u2013 Les douleurs neuropathiques r\u00e9fractaires aux th\u00e9rapies accessibles (m\u00e9dicamenteuses ou non) ;<br>\u2013 certaines formes d\u2019\u00e9pilepsie s\u00e9v\u00e8res et pharmaco-r\u00e9sistantes ;<br>\u2013 certains sympt\u00f4mes rebelles en oncologie li\u00e9s au cancer ou \u00e0 ses traitements ;<br>\u2013 situations de soins palliatifs.<\/p>\n\n\n\n<p>Les donn\u00e9es r\u00e9colt\u00e9es lors des deux premi\u00e8res ann\u00e9es de l\u2019exp\u00e9rimentation ont \u00e9t\u00e9 \u00e9valu\u00e9es par diff\u00e9rentes \u00e9tudes, elles sont TRES POSITIVES et encourageantes pour les patients.<br>Elles montrent l\u2019EFFICACITE DU CANNABIS MEDICAL dans toutes les indications de l\u2019exp\u00e9rimentation, maintenue sur plusieurs mois chez certains patients, ainsi qu\u2019un circuit de prescription et de d\u00e9livrance s\u00e9curis\u00e9 et op\u00e9rationnel.<\/p>\n\n\n\n<p>Le cannabis m\u00e9dical \u00e9tait prescrit sous deux formes :<br>\u2013 des m\u00e9dicaments sous forme d\u2019huile de cannabis m\u00e9dical par voie orale,<br>\u2013 des pr\u00e9parations de fleurs s\u00e9ch\u00e8es de cannabis m\u00e9dical absorb\u00e9es sous forme de poudre par inhalation.<\/p>\n\n\n\n<p>Rappelons que le cannabis m\u00e9dical est contre-indiqu\u00e9 :<br>\u2013 Chez la femme enceinte et allaitante ; une contraception efficace doit \u00eatre mise en place chez les femmes en \u00e2ge de procr\u00e9er.<br>\u2013 En cas d\u2019ant\u00e9c\u00e9dents personnels de troubles psychotiques .<br>\u2013 En cas d\u2019insuffisance r\u00e9nale, h\u00e9patique ou cardiaque grave.<br>Le cannabis m\u00e9dical, surtout sur une longue p\u00e9riode, peut entrainer une d\u00e9pendance. Il a une influence sur l\u2019aptitude \u00e0 conduire des v\u00e9hicules et \u00e0 utiliser des machines car il peut provoquer une somnolence ou des \u00e9tourdissements et alt\u00e9rer la coordination, le jugement, le temps de r\u00e9ponse. Ainsi, la conduite de v\u00e9hicules \u00e9tait interdite pour les patients inclus dans l\u2019exp\u00e9rimentation.<br>Comme tout m\u00e9dicament, le cannabis m\u00e9dical doit \u00eatre pris ou administr\u00e9 en respectant les pr\u00e9cautions d\u2019emploi et peut entrainer des effets ind\u00e9sirables et peut interagir avec d\u2019autres m\u00e9dicaments ou des aliments.<\/p>\n\n\n\n<p>Nous rappelons qu\u2019il ne faut jamais interrompre brutalement un traitement et que les m\u00e9dicaments non utilis\u00e9s doivent \u00eatre rapport\u00e9s en pharmacie.<\/p>\n\n\n\n<p><br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">RESUME<\/h2>\n\n\n\n<p>Hallucinog\u00e8ne, antispasmodique et en g\u00e9n\u00e9ral interdit<\/p>\n\n\n\n<p>Le chanvre est tr\u00e8s r\u00e9pandu dans le monde entier. Certaines vari\u00e9t\u00e9s s\u00e9cr\u00e8tent une r\u00e9sine qui contient des substances tr\u00e8s actives sur le syst\u00e8me nerveux. Leur absorption par voie digestive ou respiratoire provoque selon la dose : une l\u00e9g\u00e8re ivresse, une d\u00e9sorientation dans le temps, des modifications de la perception des bruits et des couleurs, une incoordination des mouvements, de l&rsquo;angoisse, voire une v\u00e9ritable psychose. On trouve \u00e9galement dans cette r\u00e9sine des compos\u00e9s antispasmodiques et antiasthmatiques. Le chanvre \u00e0 r\u00e9sine est interdit de culture et de consommation dans la majorit\u00e9 des pays du monde mais la l\u00e9gislation \u00e9volue et une UTILISATION MEDICALE du cannabis est de plus en plus accept\u00e9e dans de nombreux pays surtout pour calmer certaines douleurs rebelles.<\/p>\n\n\n\n<p>Copyright 2024 : Dr Jean-Michel Hurtel<\/p>\n\n\n\n<p>Vous \u00eates sur www.phytomania.com<br>Plantes et m\u00e9decine,<br>site d\u00e9di\u00e9 aux plantes m\u00e9dicinales et aux huiles essentielles<br>PHYTOTHERAPIE, PLANTES MEDICINALES, AROMATHERAPIE, HUILES ESSENTIELLES<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est une toute petite famille botanique qui comprend deux genres :HUMULUS (le houblon) et CANNABIS (le chanvre), CANNABIS SATIVA=CANNABIS INDICA, CANNABACEAE. Il existe une peu de confusion sur l&rsquo;existence ou non de plusieurs esp\u00e8ces de cannabis, qui sont d\u00e9crites parfois comme de simples sous-esp\u00e8ces ou vari\u00e9t\u00e9s de Cannabis sativa.. Certains botanistes distinguent plusieurs \u00ab\u00a0types\u00a0\u00bb de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[87,86,68,54,6,82,84,62,59,2,61,81,83,44,85,60,88],"tags":[],"class_list":["post-334","post","type-post","status-publish","format-standard","hentry","category-antalgique","category-antispasmodique","category-anxiete","category-asthme-bronchique","category-cancer","category-douleurs-neuropathiques","category-epilepsie","category-etats-anxieux","category-plante-calmante","category-plante-medicinale","category-plante-sedative","category-regles-douloureuses","category-sclerose-en-plaques","category-sida","category-soins-palliatifs","category-sommeil","category-vomissements","entry"],"_links":{"self":[{"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/posts\/334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/comments?post=334"}],"version-history":[{"count":4,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/posts\/334\/revisions"}],"predecessor-version":[{"id":1745,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/posts\/334\/revisions\/1745"}],"wp:attachment":[{"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/media?parent=334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/categories?post=334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/tags?post=334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}