{"id":537,"date":"2024-06-04T07:20:31","date_gmt":"2024-06-04T05:20:31","guid":{"rendered":"https:\/\/www.phytomania.com\/plantes-medicinales\/?p=537"},"modified":"2025-11-11T10:49:11","modified_gmt":"2025-11-11T09:49:11","slug":"genevrier","status":"publish","type":"post","link":"https:\/\/www.phytomania.com\/plantes-medicinales\/genevrier\/","title":{"rendered":"GENEVRIER"},"content":{"rendered":"\n<p>Les GENEVRIERS font partie d&rsquo;une grande famille de conif\u00e8res, les cupressac\u00e9es, dans certains genres les arbres poss\u00e8dent des proportions gigantesques ou ont une long\u00e9vit\u00e9 exceptionnelle (sequoia, redwood, cypr\u00e8s).<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\" https:\/\/www.phytomania.com\/herbal-medicine\/common-juniper\/\"><img loading=\"lazy\" decoding=\"async\" width=\"32\" height=\"32\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/05\/EnglishLanguage_Flag1_26107.png\" alt=\"\" class=\"wp-image-44\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.phytomania.com\/medicina-herbaria\/enebro-comun-jinebro\/\"><img loading=\"lazy\" decoding=\"async\" width=\"32\" height=\"32\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/05\/Spain_flags_flag_8858.png\" alt=\"\" class=\"wp-image-42\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"314\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/06\/genevrier-commun.jpg\" alt=\"credit wikipedia\" class=\"wp-image-540\" srcset=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/06\/genevrier-commun.jpg 250w, https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/06\/genevrier-commun-239x300.jpg 239w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/figure>\n\n\n\n<p>Pour leur part les genevriers du genre JUNIPERUS sont d&rsquo;apparence plus modeste, 3 \u00e0 10 m voire moins, on les rencontre dans les zones temp\u00e9r\u00e9es ou froides ainsi que dans les r\u00e9gions \u00e0 climat de type m\u00e9diterran\u00e9en.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">JUNIPERUS COMMUNIS,  JUNIPERUS OXYCEDRUS,  CUPRESSACEAE<\/h2>\n\n\n\n<p>Ce sont des plantes m\u00e9dicinales ou \u00ab\u00a0magiques\u00a0\u00bb utilis\u00e9es dans beaucoup de pharmacop\u00e9es ou par les tradipraticiens.<\/p>\n\n\n\n<p>Le GENEVRIER COMMUN, Juniperus communis, se rencontre dans les r\u00e9gions temp\u00e9r\u00e9es ou froides de l&rsquo;h\u00e9misph\u00e8re Nord (dont la France), sur des terrains vari\u00e9s (sablonneux, calcaire, pentes montagneuses, Causses, bordures de for\u00eat, terrains agricoles abandonn\u00e9s).<br>Les feuilles persistantes, \u00e9troites, group\u00e9es par trois et qui pr\u00e9sentent UN SEUL sillon blanch\u00e2tre sur leur face sup\u00e9rieure, se terminent en pointe ac\u00e9r\u00e9e et piquante.<br>Il existe des pieds m\u00e2les et des pieds femelles.<br>Le fruit ( en fait un c\u00f4ne fructif\u00e8re) atteint sa maturit\u00e9 au bout de deux ans (voir 3 ans), il passe alors de la couleur verte \u00e0 une teinte bleue-violac\u00e9e presque noire d&rsquo;aspect parfois cireuse, il contient en g\u00e9n\u00e9ral trois \u00ab\u00a0noyaux\u00a0\u00bb durs entour\u00e9s d&rsquo;une pulpe un peu sucr\u00e9e, \u00e2cre et aromatique, il aromatise des plats traditionnels(choucroute) ou des alcools (gin, geni\u00e8vre).<\/p>\n\n\n\n<p>Le GENEVRIER CADE OU OXYCEDRE, Juniperus oxycedrus, est un arbuste (\u00e9galement dioique) des r\u00e9gions \u00e0 climat m\u00e9diterran\u00e9en, on le rencontre jusqu&rsquo;au Moyen-Orient. Les botanistes d\u00e9crivent des vari\u00e9t\u00e9s locales.<br>En France c&rsquo;est une plante de la guarrigue et des maquis mais aussi des causses du massif central.<br>Le genevrier cade ressemble au genevrier commun mais il est souvent de plus grande taille, les fruits sont plus gros et de couleur brune ou rouge\u00e2tre \u00e0 maturit\u00e9 ; les feuilles \u00e9troites et ac\u00e9r\u00e9es poss\u00e8dent DEUX sillons blanch\u00e2tres.<\/p>\n\n\n\n<p>Il existe beaucoup d&rsquo;autres genevriers \u00ab\u00a0m\u00e9dicinaux\u00a0\u00bb, exemples : Juniperus phoenicea ( afrique du nord),Juniperus thurifera (\u00e0 encens, Afrique du nord, r\u00e9gions m\u00e9diterran\u00e9ennes), Juniperus sabina (m\u00eames r\u00e9gions, toxique par ses baies, feuilles et huile essentielle) ainsi que beaucoup d&rsquo;esp\u00e8ces en Asie (Chine, Inde, Himalaya).<\/p>\n\n\n\n<p>Les parties utilis\u00e9es en phytoth\u00e9rapie sont les fruits ou baies de geni\u00e8vre, les feuilles, l&rsquo;huile essentielle de feuille et de baies ; dans une moindre mesure le bois ou l&rsquo;\u00e9corce.<\/p>\n\n\n\n<p>GENEVRIER COMMUN GENEVRIER CADE HUILE DE CADE BAIE DE GENIEVRE DIGESTION DIFFICILE TROUBLES URINAIRES FIEVRE TONUS PLAIES ULCERES INFECTIONS CHAMPIGNONS CUTANES ANTIFONGIQUE HUILE ESSENTIELLE DERMATOSES MEDECINE VETERINAIRE<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"http:\/\/www.imagesud.com\"><img loading=\"lazy\" decoding=\"async\" width=\"336\" height=\"280\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesudbis.jpg\" alt=\"\" class=\"wp-image-1418\" srcset=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesudbis.jpg 336w, https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesudbis-300x250.jpg 300w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><\/a><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><a href=\"http:\/\/www.imagesud.com \">http:\/\/www.imagesud.com <\/a>site partenaire de phytomania.com<\/h2>\n\n\n\n<p>COMPOSITION CHIMIQUE ET PROPRIETES<\/p>\n\n\n\n<p>JUNIPERUS COMMUNIS LE GENEVRIER COMMUN<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"406\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/06\/genevrier-commun-2.jpg\" alt=\"\" class=\"wp-image-541\" srcset=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/06\/genevrier-commun-2.jpg 350w, https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/06\/genevrier-commun-2-259x300.jpg 259w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/figure>\n\n\n\n<p>Les rameaux feuillus avec fruits contiennent :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>des tanins,<\/li>\n\n\n\n<li>des flavono\u00efdes anti-inflammatoires et protecteurs vasculaires,<\/li>\n\n\n\n<li>de l&rsquo;HUILE ESSENTIELLE(1 \u00e0 2%), dont la composition est domin\u00e9e par des monoterp\u00e8nes(75%) mais en proportion variable selon le stade v\u00e9g\u00e9tatif et la localisation g\u00e9ographique : alpha-pin\u00e8ne (10 \u00e0 70%), sabin\u00e8ne (5 \u00e0 50%), myrc\u00e8ne (1 \u00e0 20%), limon\u00e8ne (1 \u00e0 5%), beta-pin\u00e8ne (1 \u00e0 5%), faible pourcentage d&rsquo;alcools terp\u00e9niques (c\u00e9drol, terpin\u00e8ne-4-ol). A ma connaissance il n&rsquo;y a pas de compos\u00e9s c\u00e9tones toxiques.<br>Cette huile essentielle est :<\/li>\n\n\n\n<li>ANTISEPTIQUE (urinaire et digestive),<\/li>\n\n\n\n<li>inhibe le d\u00e9veloppement de nombreux champignons (ANTIFONGIQUE) notamment des champignons responsables de mycoses cutan\u00e9es (Microsporum canis et Trichophyton rubrum), mais aussi des levures (candidoses),<\/li>\n\n\n\n<li>elle est \u00e9galement ANTI-INFLAMMATOIRE ET ANTALGIQUE.<\/li>\n\n\n\n<li>les rameaux feuillus contiennent une faible quantit\u00e9 de d\u00e9soxypodophyllotoxine, substance toxique mais au potentiel anticanc\u00e9reux.<\/li>\n<\/ul>\n\n\n\n<p>Les fruits ou BAIES DE GENIEVREcontiennent des sucres et des substances am\u00e8res ainsi que de l&rsquo;huile essentielle \u00e0 la composition voisine de celle des feuilles.<br>On recueille les fruits m\u00fbrs ( bleus-noirs) et on les fait s\u00e9cher, il vaut mieux les \u00e9craser (concasser) au moment de s&rsquo;en servir sauf dans les plats traditionnels o\u00f9 on les incorpore entiers.<\/p>\n\n\n\n<p>L&rsquo; huile essentielle de baies de geni\u00e8vre est tr\u00e8s aromatique et s&rsquo;est r\u00e9v\u00e9l\u00e9e int\u00e9ressante en cas de diab\u00e8te notamment de type 2.<br>Elle retarderait le ph\u00e9nom\u00e8ne de glycation des prot\u00e9ines source de complications du diab\u00e8te.<\/p>\n\n\n\n<p>La GLYCATION ou r\u00e9action chimique de Maillard est un processus chimique naturelle qui voit l&rsquo;association entre des mol\u00e9cules de sucre et des prot\u00e9ines.<br>Les substances qui r\u00e9sultent de cette r\u00e9action naturelle sont \u00e0 l&rsquo;origine du veillissement des tissus (notamment des vaisseaux sanguins).<br>Les diab\u00e9tiques sont souvent en hyperglyc\u00e9mie et le risque de glycation des prot\u00e9ines est donc plus \u00e9l\u00e9v\u00e9 dans leur cas avec un risque augment\u00e9 d&rsquo;art\u00e9rioscl\u00e9rose, de troubles r\u00e9naux ou m\u00eame de cataracte.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"http:\/\/www.imagesud.com\"><img loading=\"lazy\" decoding=\"async\" width=\"336\" height=\"280\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesud2bis.jpg\" alt=\"\" class=\"wp-image-1415\" srcset=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesud2bis.jpg 336w, https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesud2bis-300x250.jpg 300w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><\/a><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><a href=\"http:\/\/www.imagesud.com\">http:\/\/www.imagesud.com<\/a> site partenaire de phytomania.com<\/h2>\n\n\n\n<p>JUNIPERUS OXYCEDRUS LE GENEVRIER CADE<\/p>\n\n\n\n<p>Selon une \u00e9tude en Tunisie , les feuilles de genevrier cade (m\u00e9lang\u00e9es aux fruits) contiennent de l&rsquo;huile essentielle domin\u00e9e par l&rsquo;alpha-pin\u00e8ne (27-58%) avec des composants mineurs comme le g\u00e9ranyl(2 \u00e0 7%).<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"170\" height=\"247\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/06\/genevrier-cade.jpg\" alt=\"credit wikipedia\" class=\"wp-image-538\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"290\" height=\"218\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/06\/genevrier-cade-2.jpg\" alt=\"\" class=\"wp-image-539\"\/><\/figure>\n\n\n\n<p>Mais c&rsquo;est surtout le BOIS DU GENEVRIER CADE qui est traditionnellement utilis\u00e9 :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>sous forme de poudre (encens),<\/li>\n\n\n\n<li>ou pour obtenir une \u00ab\u00a0huile\u00a0\u00bb par pyrolyse (chauffage et distillation s\u00e8che) du bois.<\/li>\n<\/ul>\n\n\n\n<p>Cette HUILE DE CADE est une substance traditionnellement utilis\u00e9e par voie externe aussi bien chez les humains que les animaux.<\/p>\n\n\n\n<p>C&rsquo;est un liquide tr\u00e8s color\u00e9 \u00e0 l&rsquo;odeur forte de bois brul\u00e9 ou de goudron qui contient des sesquiterp\u00e8nes et des ph\u00e9nols tr\u00e8s antiseptiques (gaiacol, cr\u00e9sol), et dont l&rsquo;odeur \u00e9loignent \u00e9galement les insectes.<br>Mais les produits de pyrolyse du bois sont nombreux et comprennent aussi des SUBSTANCES TOXIQUES ET CANCERIGENES (notamment des hydrocarbures comme les pyr\u00e8nes canc\u00e9rig\u00e8nes).<br>Cette huile de cade poss\u00e8de plusieurs noms au Magreb o\u00f9 elle est connue et couramment utilis\u00e9e citons : Katran ou Katrane ou El Guetrane.<\/p>\n\n\n\n<p>UTILISATIONS<\/p>\n\n\n\n<p>JUNIPERUS COMMUNIS LE GENEVRIER COMMUN<\/p>\n\n\n\n<p>genevrier commun: cr\u00e9dit WikipediaPlanche botanique de genevrier commun Juniperus communis<br>Le genevrier est une plante m\u00e9dicinale traditionnelle, on l&rsquo;UTILISAIT AUTREFOIS pour soigner de nombreuses affections :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>troubles digestifs,<\/li>\n\n\n\n<li>urinaires,<\/li>\n\n\n\n<li>infections (m\u00eame la tuberculose), contre les fi\u00e8vres en g\u00e9n\u00e9ral (y compris le paludisme),<\/li>\n\n\n\n<li>troubles broncho-pulmonaires chroniques,<\/li>\n\n\n\n<li>comme diur\u00e9tique (y compris en cas d&rsquo;insuffisance cardiaque)<\/li>\n\n\n\n<li>ou pour soigner les rhumatismes et les douleurs articulaires chroniques.<br>Beaucoup de ces indications ne sont plus d&rsquo;actualit\u00e9 n\u00e9anmoins les baies de genevrier sont utiles pour :<\/li>\n\n\n\n<li>faciliter la DIGESTION (stimulant digestif), \u00e9galement en cas de fermentations intestinales,<\/li>\n\n\n\n<li>renforcer le \u00ab\u00a0TONUS\u00a0\u00bb physique, notamment en cas de viroses saisonni\u00e8res de type grippal, de rhume,<\/li>\n\n\n\n<li>soigner une INFECTION mineure des voies urinaires (mais PAS en cas d&rsquo;insuffisance r\u00e9nale), drainer les voies urinaires en cas de lithiase (calculs) urinaire r\u00e9cidivante,<\/li>\n\n\n\n<li>en cas de DIABETE de type 2 surtout pour \u00e9viter les complications vasculaires du diab\u00e8te et peut-\u00eatre aussi pour augmenter l&rsquo;efficacit\u00e9 de l&rsquo;insuline ( l&rsquo;inefficacit\u00e9 ou\u00a0\u00bbr\u00e9sistance\u00a0\u00bb \u00e0 l&rsquo;insuline est un des probl\u00e8mes graves du diab\u00e8te de type 2),<\/li>\n\n\n\n<li>l&rsquo;HUILE ESSENTIELLE de genevrier est antiseptique, antifongique (mais moins que l&rsquo;huile de \u00ab\u00a0tea tree\u00a0\u00bb), r\u00e9pulsive pour certains insectes mais sert \u00e9galement en cas de douleurs de type rhumatismale ou arthrosique en applications locales.<\/li>\n<\/ul>\n\n\n\n<p>EXEMPLES DE POSOLOGIE<\/p>\n\n\n\n<p>-INFUSION de baies de genevrier ( concass\u00e9es et \u00e9ventuellement m\u00e9lang\u00e9es aux feuilles) : une dizaine de grammes de baies dans 1\/4 de litre d&rsquo;eau tr\u00e8s chaude, infuser 10 \u00e0 15 mn, \u00e0 consommer dans l journ\u00e9e ( fin de repas, suite de grippe, irritation urinaire, douleurs rhumatismales).<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>VIN DE GENIEVRE : 1 litre de vin blanc et 30 \u00e0 50 gr de baies concass\u00e9es, laisser mac\u00e9rer 15 jours en remuant de temps en temps, filtrer, sucrer selon son go\u00fbt et conserver au frais : un verre de vin par jour.<\/li>\n\n\n\n<li>TEINTURE MERE de genevrier : 30 gouttes 2 \u00e0 3 fois par jour. on peut \u00e9galement faire une TEINTURE ALCOOLIQUE \u00ab\u00a0domestique\u00a0\u00bb de baies de geni\u00e8vre ( 100 gr de baies concass\u00e9es dans 1 litre d&rsquo;alcool \u00e0 45-55\u00b0 (rhum), laisser mac\u00e9rer 10 \u00e0 15 jours, filtrer, conserver \u00e0 l&rsquo;abri de la lumi\u00e8re.<\/li>\n\n\n\n<li>HUILE ESSENTIELLE de genevrier commun :<\/li>\n\n\n\n<li>quelques gouttes en application avec massage (\u00e9ventuellement apr\u00e8s dilution dans une huile v\u00e9g\u00e9tale) sur les zones douloureuses articulaires ou musculaires,<\/li>\n\n\n\n<li>quelques gouttes en application directe sur des plaies enflamm\u00e9es ou infect\u00e9es, sur des mycoses de la peau, du cuir chevelu ou des ongles (mais c&rsquo;est moins efficace que l&rsquo;huile de tea tree, Melaleuca alternifolia)<\/li>\n<\/ul>\n\n\n\n<p>PRECAUTIONS D UTILISATIONS : Les extraits de genevrier ou de baies de geni\u00e8vre sont contre-indiqu\u00e9s chez la femme enceinte ou allaitant ainsi que chez les personnes qui pr\u00e9sente une insuffisance r\u00e9nale, ou des troubles r\u00e9naux chroniques.<br>D&rsquo;une fa\u00e7on plus g\u00e9n\u00e9rale il faut respecter les doses cit\u00e9es dans les exemples de posologie, ne pas faire des cures \u00ab\u00a0prolong\u00e9es\u00a0\u00bb d&rsquo;extraits de genevrier (15 jours maximum avec un mois entre chaque cure) et arr\u00eater imm\u00e9diatement en cas d&rsquo;h\u00e9maturie (sang dans les urines) ou si l&rsquo;on d\u00e9tecte la pr\u00e9sence d&rsquo;albumine dans l&rsquo;urine.<\/p>\n\n\n\n<p>JUNIPERUS OXYCEDRUS LE GENEVRIER CADE<\/p>\n\n\n\n<p>L&rsquo;HUILE DE CADE est connue et utilis\u00e9e depuis fort longtemps aussi bien pour soigner les humains que les animaux.<\/p>\n\n\n\n<p>On trouve encore dans les guarrigues ou les maquis d&rsquo;anciens \u00ab\u00a0fours \u00e0 cade\u00a0\u00bb ou l&rsquo;on br\u00fblait du bois (\u00e0 l&rsquo;\u00e9touff\u00e9e) pour recueillir l&rsquo;huile de cade brute, liquide plus moins visqueux et color\u00e9.<\/p>\n\n\n\n<p>Il est assez facile d&rsquo;en produire, il suffit de chauffer du bois de cade dans un recipient bien ferm\u00e9 mais qui poss\u00e8de une petite ouverture reli\u00e9e \u00e0 un tuyau dans lequel les vapeurs de distillation s\u00e8che se condenseront , c&rsquo;est la m\u00eame technique que pour obtenir du \u00ab\u00a0goudron de Norv\u00e8ge\u00a0\u00bb avec des r\u00e9sineux.<\/p>\n\n\n\n<p>Cette huile de cade poss\u00e8de des VERTUS ANTISEPTIQUES CICATRISANTES ET INSECTIFUGES , et elle agit (parfois) sur les dermatoses chroniques (ecz\u00e9ma, dishydrose, psoriasis, dermite s\u00e9borrh\u00e9ique).<\/p>\n\n\n\n<p>ON NE LA PRESCRIT PLUS EN FRANCE CHEZ LES HUMAINS , car elle contient (de fa\u00e7on irr\u00e9guli\u00e8re selon le proc\u00e9d\u00e9 de pyrog\u00e9nation) des substances canc\u00e9rig\u00e8nes qui rendent son emploi dangereux alors qu&rsquo;il existe d&rsquo;autres m\u00e9dicaments pour soigner des plaies, ulc\u00e8res ou dermatoses.<\/p>\n\n\n\n<p>Mais elle est toujours employ\u00e9es CHEZ LES ANIMAUX pour soigner des plaies, des ulc\u00e9rations chroniques, des infections (surtout des pieds (chevaux, moutons, bovins), ou des pattes (poules), ainsi que pour \u00e9loigner des insectes parasites ou irritants pour les chevaux ou le b\u00e9tail.<br>.<br>On l&#8217;emploie en g\u00e9n\u00e9ral dilu\u00e9e dans une huile v\u00e9g\u00e9tale ou m\u00e9lang\u00e9e \u00e0 de l&rsquo;argile ou une poudre min\u00e9rale neutre.<\/p>\n\n\n\n<p>Chez les chevaux ( pour \u00e9loigner les insectes) il faut toujours v\u00e9rifier l&rsquo;absence de r\u00e9action d&rsquo;intol\u00e9rance en faisant une application limit\u00e9e sur une partie fine de la peau , ne pas en mettre sur les muqueuses ou trop pr\u00e8s des yeux et penser que c&rsquo;est une liquide color\u00e9 qui tache .<\/p>\n\n\n\n<p>AUTRES UTILISATIONS DES GENEVRIERS<\/p>\n\n\n\n<p>L&rsquo; alcool geni\u00e8vre ainsi que d&rsquo;autres alcools traditionnels ( exemples : gin, aquavit) sont des alcools de grain qui sont aromatis\u00e9s secondairement par une mac\u00e9ration ou des extraits de baies de geni\u00e8vre.<br>La baie de geni\u00e8vre aromatise traditionnellement la choucroute et certains p\u00e2t\u00e9s ou plats riches en graisse et f\u00e9culents, elle en favorise la digestion (peut-\u00eatre).<\/p>\n\n\n\n<p>Les cendres des rameaux feuillus de genevrier contiennent des sels min\u00e9raux( calcium, potassium, sodium) et sont traditionnellement consid\u00e9r\u00e9es comme diur\u00e9tiques .<\/p>\n\n\n\n<p>Dans beaucoup de pays les rameaux de genevrier sont brul\u00e9s \u00e0 la mani\u00e8re de l&rsquo;encens pour assainir l&rsquo;atmosph\u00e8re ( au sens propre et figur\u00e9 (\u00e9loigner les mauvais esprits)).<br>C&rsquo;est une pratique courante notamment dans les r\u00e9gions himalayennes o\u00f9 l&rsquo;on pratique le Bouddhisme Tib\u00e9tain.<\/p>\n\n\n\n<p>CULTURE DES GENEVRIERS<\/p>\n\n\n\n<p>Les diff\u00e9rentes esp\u00e8ces de genevriers sont des arbres, tr\u00e8s r\u00e9sistants, d\u00e9coratifs, \u00e0 la croissance lente et au feuillage persistant, on en fait donc des haies, des buissons ou des \u00ab\u00a0bonza\u00ef\u00a0\u00bb.<br>On peut les faire pousser \u00e0 partir du fruit mais il faut \u00eatre patient car la germination peut prendre plusieurs ann\u00e9es et le d\u00e9but de croissance est tr\u00e8s lent.<br>Il est plus facile de d\u00e9terrer et transplanter un jeune genevrier sauvage!!<\/p>\n\n\n\n<p>RESUME<\/p>\n\n\n\n<p>LES GENEVRIERS PLANTES MEDICINALES TRADITIONNELLES<br>IL existe de nombreuses esp\u00e8ces de genevrier (Juniperus), les plus utilis\u00e9s en Europe sont le genevrier commun et le genevrier cade.<br>Les baies de genevrier commun (geni\u00e8vre) facilitent la digestion, et aident \u00e0 d\u00e9sinfecter les voies urinaires et le syst\u00e8me digestif. L&rsquo;huile essentielle de genevrier commun est antiseptique, fongicide et calme les douleurs de type rhumatismal.<br>On extrait par chauffage et distillation une huile du bois de cade. Elle est antiseptique, cicatrisante, \u00e9loigne les insectes et calme certaines dermatoses.<br>Comme l&rsquo;huile de cade peut contenir des substances canc\u00e9rig\u00e8nes on ne l&rsquo;utilise plus en m\u00e9decine humaine mais elle sert encore \u00e0 soigner les animaux.<\/p>\n\n\n\n<p>Copyright 2023 : Dr Jean-Michel Hurtel<\/p>\n\n\n\n<p>Vous \u00eates sur www.phytomania.com<br>site d\u00e9di\u00e9 aux plantes m\u00e9dicinales et aux huiles essentielles<br>PHYTOTHERAPIE, PLANTES MEDICINALES, AROMATHERAPIE, HUILES ESSENTIELLES<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les GENEVRIERS font partie d&rsquo;une grande famille de conif\u00e8res, les cupressac\u00e9es, dans certains genres les arbres poss\u00e8dent des proportions gigantesques ou ont une long\u00e9vit\u00e9 exceptionnelle (sequoia, redwood, cypr\u00e8s). Pour leur part les genevriers du genre JUNIPERUS sont d&rsquo;apparence plus modeste, 3 \u00e0 10 m voire moins, on les rencontre dans les zones temp\u00e9r\u00e9es ou froides [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[72,45,78,37,119,38,28,24,48,111,76,30,4,74,33,23,91,128,127,93,77,7],"tags":[],"class_list":["post-537","post","type-post","status-publish","format-standard","hentry","category-acne-furonculose","category-anti-inflammatoire","category-antiseptique-urinaire","category-antiviral","category-augmenter-le-tonus","category-cicatrisant","category-cystite-banale","category-diabete","category-digestion","category-diuretique","category-eczema","category-episode-febrile","category-huile-essentielle","category-huile-essentielle-antiseptique","category-immunostimulant","category-infections-urinaires","category-insecticide-repulsif","category-katran-ou-katrane","category-medecine-veterinaire","category-mycose-cutanee","category-rhumatisme","category-troubles-digestifs","entry"],"_links":{"self":[{"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/posts\/537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/comments?post=537"}],"version-history":[{"count":4,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/posts\/537\/revisions"}],"predecessor-version":[{"id":1686,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/posts\/537\/revisions\/1686"}],"wp:attachment":[{"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/media?parent=537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/categories?post=537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/tags?post=537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}