{"id":55,"date":"2024-05-16T13:26:59","date_gmt":"2024-05-16T11:26:59","guid":{"rendered":"https:\/\/www.phytomania.com\/plantes-medicinales\/?p=55"},"modified":"2025-11-13T11:47:10","modified_gmt":"2025-11-13T10:47:10","slug":"achillee-millefeuille","status":"publish","type":"post","link":"https:\/\/www.phytomania.com\/plantes-medicinales\/achillee-millefeuille\/","title":{"rendered":"ACHILLEE MILLEFEUILLE"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><a href=\" https:\/\/www.phytomania.com\/herbal-medicine\/yarrow\/\"><img loading=\"lazy\" decoding=\"async\" width=\"32\" height=\"32\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/05\/EnglishLanguage_Flag1_26107.png\" alt=\"\" class=\"wp-image-44\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\" https:\/\/www.phytomania.com\/medicina-herbaria\/milenrama\/\"><img loading=\"lazy\" decoding=\"async\" width=\"32\" height=\"32\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/05\/Spain_flags_flag_8858.png\" alt=\"\" class=\"wp-image-42\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"259\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/05\/achillea_millefolium.jpg\" alt=\"\" class=\"wp-image-229\"\/><\/figure>\n\n\n\n<p>Il existe plus de 150 esp\u00e8ces d&rsquo;achill\u00e9es, r\u00e9pandues un peu partout dans le monde, mais celle qui est la plus utilis\u00e9e comme plante m\u00e9dicinale est l&rsquo;achill\u00e9e millefeuille.<\/p>\n\n\n\n<p>C&rsquo;est une plante vivace par son rhizome \u00e0 tiges dress\u00e9es souvent uniques ou peu ramifi\u00e9es, aux feuilles alternes finement d\u00e9coup\u00e9es (donnant l&rsquo;apparence de nombreuses petites feuilles) et \u00e0 l&rsquo;inflorescence en capitules l\u00e9g\u00e8rement bomb\u00e9s qui regroupent de 10 \u00e0 30 petites fleurs (ou fleurons) blanches ou roses, parfois teint\u00e9es de jaune ou de pourpre.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>L&rsquo;achill\u00e9e millefeuille, ACHILLEA MILLEFOLIUM, COMPOSITAE,  est tr\u00e8s r\u00e9pandue dans la majorit\u00e9 des pays de l&rsquo;h\u00e9miph\u00e8re Nord temp\u00e9r\u00e9s (m\u00eame froids) ou de type m\u00e9diterran\u00e9en ; on la trouve \u00e0 l&rsquo;\u00e9tat sauvage ou cultiv\u00e9e dans les jardins.<\/p>\n\n\n\n<p>Elle a \u00e9t\u00e9 introduite en Am\u00e9rique du Sud et dans le Pacifique (Australie et Nouvelle Z\u00e9lande).<\/p>\n\n\n\n<p>L&rsquo;achill\u00e9e millefeuille est connue comme une plante m\u00e9dicinale dans toutes les r\u00e9gions o\u00f9 on la trouve ( m\u00eame les hommes de N\u00e9anderthal s&rsquo;en servaient!): les parties utilis\u00e9es en phytoth\u00e9rapie sont les sommit\u00e9es fleuries et leur huile essentielle ainsi que les feuilles.<\/p>\n\n\n\n<p>Certaines personnes allergiques aux asteraceae le sont \u00e9galement \u00e0 l&rsquo;achill\u00e9e.<\/p>\n\n\n\n<p>ACHILLEE MILLEFEUILLE CICATRISANT HEMOSTATIQUE SAIGNEMENT DE NEZ ANTISPASMODIQUE DIGESTIF DYSMENORRHEE DIURETIQUE HYPERTENSION MODEREE CYSTITE<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"http:\/\/www.imagesud.com\"><img loading=\"lazy\" decoding=\"async\" width=\"336\" height=\"280\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesudbis.jpg\" alt=\"\" class=\"wp-image-1418\" srcset=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesudbis.jpg 336w, https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesudbis-300x250.jpg 300w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><\/a><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><a href=\"http:\/\/www.imagesud.com\">http:\/\/www.imagesud.com<\/a> site partenaire de phytomania.com<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>COMPOSITION CHIMIQUE ET PROPRIETES<\/strong><\/h2>\n\n\n\n<p><strong>FEUILLES ET FLEURS D&rsquo;ACHILLEE MILLEFEUILLE<\/strong><\/p>\n\n\n\n<p>L&rsquo;achill\u00e9e millefeuille ne contient pas de substance pharmacologique importante qui lui soit sp\u00e9cifique mais plusieurs classes de compos\u00e9s actifs et int\u00e9ressants par leurs propri\u00e9t\u00e9s surtout en association :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>des lactones sesquiterp\u00e9niques (exemple : guaianolides, germacranolides), compos\u00e9s amers (certains agissent sur l&rsquo;activit\u00e9 h\u00e9patique ou la digestion), consid\u00e9r\u00e9s comme anti-inflammatoires et source potentielle de nouveaux m\u00e9dicaments dont des antileuc\u00e9miques,<\/li>\n\n\n\n<li>des flavono\u00efdes l\u00e9g\u00e8rement antispasmodiques(surtout des fibres lisses), antalgiques quand ils l\u00e8vent le spasme douloureux et pour certains, r\u00e9gulateurs hormonaux,<\/li>\n\n\n\n<li>des tanins anti-inflammatoires, antiseptiques et cicatrisants,<\/li>\n\n\n\n<li>de l&rsquo;huile essentielle,<\/li>\n\n\n\n<li>de la b\u00e9tonicine ou achill\u00e9ine , h\u00e9mostatique et possible adjuvant des traitements antibiotiques par sa capacit\u00e9 (in vitro) \u00e0 contrer l&rsquo;apparition des r\u00e9sistances bact\u00e9riennes.<\/li>\n<\/ul>\n\n\n\n<p>L&rsquo;achill\u00e9e est \u00e9tudi\u00e9e dans de nombreux pays (notamment en Asie) et la liste des propri\u00e9t\u00e9s m\u00e9dicinales potentielles de cette plante ou de ses extraits est int\u00e9ressante :<\/p>\n\n\n\n<p>-anti-spasmodique (et donc souvent antalgique) des voies g\u00e9nitales, digestives et respiratoires (antitussif),<\/p>\n\n\n\n<p>-anti-hypertensive et facilitant la lev\u00e9e du spasme bronchique (anti-asthmatique par action sur les r\u00e9cepteurs beta adr\u00e9nergiques),<\/p>\n\n\n\n<p>-diur\u00e9tique et d\u00e9sinfectant urinaire,<\/p>\n\n\n\n<p>-anti-inflammatoire, pi\u00e9geur de radicaux libres,<\/p>\n\n\n\n<p>-protecteur h\u00e9patique,<\/p>\n\n\n\n<p>-h\u00e9mostatique,<\/p>\n\n\n\n<p>-astringent et antiseptique,<\/p>\n\n\n\n<p>-r\u00e9gulateur hormonal f\u00e9minin,<\/p>\n\n\n\n<p>-et peut-\u00eatre l\u00e9g\u00e8rement anxiolytique<\/p>\n\n\n\n<p><strong>HUILE ESSENTIELLE D&rsquo;ACHILLEE MILLEFEUILLE, ACHILLEA MILLEFOLIUM<\/strong><\/p>\n\n\n\n<p>L&rsquo;huile essentielle d&rsquo;achill\u00e9e millefeuille a une composition assez variable selon la provenance g\u00e9ographique de la plante, ses conditions de culture ou du fait qu&rsquo;il s&rsquo;agit de vari\u00e9t\u00e9s voire de sous-esp\u00e8ces.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>elle est domin\u00e9e par des sesquiterp\u00e8nes dont certains, quand ils sont pr\u00e9sents, lui donne une belle et rare couleur bleue fonc\u00e9e,<\/li>\n\n\n\n<li>elle contient des terp\u00e8nes et terp\u00e9nols antiseptiques (pin\u00e8ne, sabin\u00e8ne, linalol) ainsi que de l&rsquo;eucalyptol (1-8 cin\u00e9ole), antiseptique respiratoire et eupn\u00e9ique.<\/li>\n\n\n\n<li>mais elle contient aussi du camphre et des c\u00e9tones ce qui limite son usage en interne car cette fraction de l&rsquo;huile essentielle est neurotoxique (et \u00e9pileptog\u00e8ne), peut-\u00eatre h\u00e9patotoxique ou canc\u00e9rog\u00e8ne et sans doute abortive.<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"http:\/\/www.imagesud.com\"><img loading=\"lazy\" decoding=\"async\" width=\"336\" height=\"280\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesud2bis.jpg\" alt=\"\" class=\"wp-image-1415\" srcset=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesud2bis.jpg 336w, https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesud2bis-300x250.jpg 300w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><\/a><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><a href=\"http:\/\/www.imagesud.com\">http:\/\/www.imagesud.com<\/a> site partenaire de phytomania.com<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>La concentration de la plante en huile essentielle est faible, ce qui permet une utilisation sans danger de l&rsquo;achill\u00e9e millefeuille, plante enti\u00e8re ou sous forme de poudre, d&rsquo;infusion ou d\u00e9coction aqueuse, de teinture m\u00e8re, de jus de plante fraiche.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>UTILISATIONS<\/strong><\/h2>\n\n\n\n<p>L&rsquo;achill\u00e9e millefeuille est traditionnellement une plante d&rsquo;usage externe pour soigner les plaies, pour arr\u00eater les saignements .<br>Elle \u00e9tait utilis\u00e9e de fa\u00e7on courante pour soigner les bless\u00e9s au combat ou les blessures de la vie quotidienne ou professionnelle ( herbe aux coupures, herbe aux charpentiers).<\/p>\n\n\n\n<p>Ces indications restent valable mais on lui en ajoute d&rsquo;autres moins sp\u00e9cifiques.<\/p>\n\n\n\n<p>L&rsquo;achill\u00e9e millefeuille et ses extraits permettent de contr\u00f4ler voir de gu\u00e9rir de nombreux troubles pathologiques chroniques sans avoir recours aux m\u00e9dicaments de synth\u00e8se peut-\u00eatre d&rsquo;action plus puissante et rapide mais aux effets secondaires ind\u00e9sirables.<br><strong><br>USAGE EXTERNE de l&rsquo;achill\u00e9e millefeuille, Achillea millefolium<\/strong><\/p>\n\n\n\n<p>Plaies m\u00eame avec saignements, saignements de nez (\u00e9pistaxis).<\/p>\n\n\n\n<p>C&rsquo;est l&rsquo;utilisation classique, un peu d\u00e9pass\u00e9e pour la plaie banale mais utile en cas de saignement de nez qui a du mal \u00e0 s&rsquo;arr\u00eater ou qui est r\u00e9cidivant.<br>On utilise le jus des feuilles en application directe, la d\u00e9coction ou pour le saignement de nez la feuille roul\u00e9e et l\u00e9g\u00e8rement \u00e9cras\u00e9e en tampon-bouchon \u00e0 l&rsquo;int\u00e9rieur de la narine qui saigne.<br>On garde ce pansement nasal plusieurs heures avant de le retirer avec pr\u00e9caution pour \u00e9viter de faire saigner \u00e0 nouveau la plaque vasculaire nasale.<\/p>\n\n\n\n<p><strong>USAGE INTERNE de l&rsquo;achill\u00e9e millefeuille, Achillea millefolium<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>SPASMES digestifs isol\u00e9s du colon (gros intestin), de l&rsquo;estomac (parfois assez douloureux), ou des voies biliaires (douleurs au niveau de la v\u00e9sicule biliaire, spasme du sphincter d&rsquo;oddi)<\/li>\n\n\n\n<li>certaines DOULEURS MENSTRUELLES ou DYSMENORRHEES (douleurs au moment des r\u00e8gles) y sont sensibles mais pas en cas d&rsquo;endom\u00e9triose,<\/li>\n\n\n\n<li>CYSTITE BANALE, surtout chez la femme, sans fi\u00e8vre et avec de urines non purulentes et en l&rsquo;absence d&rsquo; h\u00e9maturie (sang dans l&rsquo;urine),<\/li>\n\n\n\n<li>INSUFFISANCE HEPATIQUE . On peut essayer aussi l&rsquo;achill\u00e9e en cas de troubles digestifs li\u00e9s \u00e0 une insuffisance de l&rsquo;activit\u00e9 du foie : digestion lente des graisses, migraine digestive, bouche p\u00e2teuse et langue saburrale avec mauvaise haleine.<\/li>\n<\/ul>\n\n\n\n<p>D&rsquo;autre indications sont possibles mais moins bien document\u00e9es et je n&rsquo;en ai pas l&rsquo;exp\u00e9rience : en cas d&rsquo;hypertension art\u00e9rielle, d&rsquo;asthme, comme anxiolytique ou pour att\u00e9nuer les douleurs articulaires.<\/p>\n\n\n\n<p><strong>Exemples de POSOLOGIE <\/strong>:<br>L&rsquo;achill\u00e9e millefeuille peut \u00eatre employ\u00e9e fraiche, s\u00e8che ou sous forme d&rsquo;extrait notamment de teinture alcoolique facile \u00e0 r\u00e9aliser chez soi car cette plante ne pr\u00e9sente pas de toxicit\u00e9 notable (hormis son huile essentielle).<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>INFUSION (5mn) ou DECOCTION (15mn),<\/strong> exemple : 40 \u00e0 50g de sommit\u00e9es fleuries s\u00e8ches avec quelques feuilles ou 150 \u00e0 200g de plante fraiche dans un litre d&rsquo;eau tr\u00e8s chaude ou bouillante pour la d\u00e9coction.<br>Une tasse d&rsquo;infusion 2 \u00e0 4 fois par jour surtout pour les troubles spasmodiques.<br>La d\u00e9coction est plut\u00f4t destin\u00e9e \u00e0 l&rsquo;usage externe, nettoyage des plaies mais aussi en compresse sur des zones contuses, des ulc\u00e8res chroniques, des gercures.<\/li>\n\n\n\n<li><strong>TEINTURE ALCOOLIQUE <\/strong>et teinture m\u00e8re, g\u00e9n\u00e9ralement au 1\/10 mais que l&rsquo;on peut r\u00e9aliser au 1\/5 : en application locale sur les plaies ou par voie buccale : 30 \u00e0 50 gouttes 3 \u00e0 4 fois par jour.<\/li>\n<\/ul>\n\n\n\n<p>il existe dans le commerce des pr\u00e9parations toutes faites d&rsquo;extrait d achill\u00e9e millefeuille parfois en association avec d&rsquo;autre plantes antispasmodiques ou vuln\u00e9raires, suivre leur indication de posologie.<\/p>\n\n\n\n<p><strong>HUILE ESSENTIELLE d&rsquo;achill\u00e9e millefeuille Achillea millefolium<\/strong><\/p>\n\n\n\n<p>Nous ne pr\u00e9conisons pas cette huile essentielle par voie interne.<\/p>\n\n\n\n<p>En utilisation externe elle est cicatrisante, s&rsquo;associe \u00e0 d&rsquo;autre huiles essentielles pour soigner les peaux abim\u00e9es, les petites infections cutan\u00e9es r\u00e9cidivantes (nuque, zones de frottement).<\/p>\n\n\n\n<p>Contre-indiqu\u00e9e chez les femmes enceintes ou allaitant.<br><br><strong>CULTURE et utilisation dans les jardins de l&rsquo;achill\u00e9e millefeuille<\/strong><\/p>\n\n\n\n<p>L&rsquo;achill\u00e9e millefeuille est une plante de plein soleil tr\u00e8s peu exigeante sur la qualit\u00e9 du sol mais qui ne supporte pas les sols gorg\u00e9s d&rsquo;eau et non drain\u00e9s,.<br>Elle peut coloniser des zones tr\u00e8s d\u00e9grad\u00e9es et am\u00e9liorer les sols gr\u00e2ce \u00e0 ces racines assez profondes.<\/p>\n\n\n\n<p>Elle se propage par semis, ou en divisant des plants-m\u00e8res, ou m\u00eame en utilisant des fragments de rhizome.<\/p>\n\n\n\n<p>C&rsquo;est une plante qui peut devenir envahissante.<\/p>\n\n\n\n<p>Il existe des vari\u00e9t\u00e9s d\u00e9coratives par la couleur de leurs inflorescences.<\/p>\n\n\n\n<p>Elle serait r\u00e9pulsive pour certains insectes ravageurs des cultures mais attireraient les coccinelles.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">RESUME<\/h2>\n\n\n\n<p><strong>Achill\u00e9e millefeuille, cicatrisante, h\u00e9mostatique et antispasmodique<\/strong><br>L&rsquo;achill\u00e9e millefeuille est connue depuis l&rsquo;antiquit\u00e9 comme plante cicatrisante et pour soigner les blessures et arr\u00eater les h\u00e9morragies, c&rsquo;est aussi une plante antispasmodique non toxique soignant les spasmes digestifs et g\u00e9nitaux. Elle est mod\u00e9r\u00e9ment diur\u00e9tique et d\u00e9sinfectante.<br>Son huile essentielle potentiellement toxique est r\u00e9serv\u00e9e \u00e0 l&rsquo;usage externe.<\/p>\n\n\n\n<p>Copyright 2023 : Dr Jean-Michel Hurtel<\/p>\n\n\n\n<p>Vous \u00eates sur www.phytomania.com<br>site d\u00e9di\u00e9 aux plantes m\u00e9dicinales et aux huiles essentielles<br>PHYTOTHERAPIE, PLANTES MEDICINALES, AROMATHERAPIE, HUILES ESSENTIELLES<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il existe plus de 150 esp\u00e8ces d&rsquo;achill\u00e9es, r\u00e9pandues un peu partout dans le monde, mais celle qui est la plus utilis\u00e9e comme plante m\u00e9dicinale est l&rsquo;achill\u00e9e millefeuille. C&rsquo;est une plante vivace par son rhizome \u00e0 tiges dress\u00e9es souvent uniques ou peu ramifi\u00e9es, aux feuilles alternes finement d\u00e9coup\u00e9es (donnant l&rsquo;apparence de nombreuses petites feuilles) et \u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26,28,2,29,27,7],"tags":[],"class_list":["post-55","post","type-post","status-publish","format-standard","hentry","category-astringent-antihemorragique","category-cystite-banale","category-plante-medicinale","category-protection-hepatique","category-spasmes-digestifs","category-troubles-digestifs","entry"],"_links":{"self":[{"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/posts\/55","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/comments?post=55"}],"version-history":[{"count":7,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/posts\/55\/revisions"}],"predecessor-version":[{"id":1799,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/posts\/55\/revisions\/1799"}],"wp:attachment":[{"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/media?parent=55"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/categories?post=55"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/tags?post=55"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}