{"id":890,"date":"2024-06-20T19:25:03","date_gmt":"2024-06-20T17:25:03","guid":{"rendered":"https:\/\/www.phytomania.com\/plantes-medicinales\/?p=890"},"modified":"2025-11-09T11:11:58","modified_gmt":"2025-11-09T10:11:58","slug":"plantain","status":"publish","type":"post","link":"https:\/\/www.phytomania.com\/plantes-medicinales\/plantain\/","title":{"rendered":"PLANTAIN"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.phytomania.com\/medicina-herbaria\/llanten\/\"><img loading=\"lazy\" decoding=\"async\" width=\"32\" height=\"32\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/06\/Spain_flags_flag_8858.png\" alt=\"\" class=\"wp-image-744\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.phytomania.com\/herbal-medicine\/plantain\/\"><img loading=\"lazy\" decoding=\"async\" width=\"32\" height=\"32\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/06\/EnglishLanguage_Flag1_26107.png\" alt=\"\" class=\"wp-image-740\"\/><\/a><\/figure>\n\n\n\n<p>Il existe dans le monde plusieurs centaines d&rsquo;esp\u00e8ces de PLANTAINS (PLANTAGINACEAE).<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"278\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/06\/plantain.jpg\" alt=\"\" class=\"wp-image-892\" srcset=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/06\/plantain.jpg 350w, https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/06\/plantain-300x238.jpg 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/figure>\n\n\n\n<p>PLANTO LANCEOLATA plantain lanc\u00e9ol\u00e9<\/p>\n\n\n\n<p>Les plantains des r\u00e9gions temp\u00e9r\u00e9es sont des plantes vivaces communes et qui sont adaptables au climat tropical ou subtropical on les retrouve donc dans le monde entier sauf les r\u00e9gions tr\u00e8s froides ou trop chaudes.<\/p>\n\n\n\n<p>Elles se propagent par leur petites graines qui restent vivantes pendant longtemps et qui se m\u00e9langent aux gramin\u00e9es (bl\u00e9, orge ,avoine) .PLANTAGO MAJOR, le grand plantain et PLANTAGO LANCEOLATA,le plantain lanc\u00e9ol\u00e9 ainsi que des formes interm\u00e9diaires (Plantago intermedia) sont originaires d\u2019Europe mais maintenant pr\u00e9sents aussi bien en Chine, aux Antilles qu\u2019en Nouvelle-Cal\u00e9donie.<\/p>\n\n\n\n<p>Ce sont de petites plantes vivaces, sans tiges, aux feuilles en rosette, ovales pour le grand plantain, allong\u00e9es et \u00e9troites pour le plantain lanc\u00e9ol\u00e9.<br>Les fleurs sont petites, r\u00e9unies en \u00e9pis allong\u00e9s de 10 \u00e0 15 cm pour le grand plantain, ou ovo\u00efdes de 1 \u00e0 2 cm pour le plantain lanc\u00e9ol\u00e9, sur une tige non ramifi\u00e9e.<br>Les graines sont nombreuses, de tr\u00e8s petite taille et se diss\u00e9minent facilement.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"165\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/06\/plantago-major.jpg\" alt=\"\" class=\"wp-image-891\"\/><\/figure>\n\n\n\n<p>PLANTAGO MAJOR ou grand plantain<\/p>\n\n\n\n<p>PLANTAIN PLANTAGO PLANTAIN LANCEOLE GRAND PLANTAIN VULNERAIRE ANTIBIOTIQUE ANTIINFLAMMATOIRE COLLYRE PANSEMENT SALADE VITAMINEE<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"http:\/\/www.imagesud.com\"><img loading=\"lazy\" decoding=\"async\" width=\"336\" height=\"280\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesudbis.jpg\" alt=\"\" class=\"wp-image-1418\" srcset=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesudbis.jpg 336w, https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesudbis-300x250.jpg 300w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><\/a><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><a href=\"http:\/\/www.imagesud.com\">http:\/\/www.imagesud.com<\/a> site partenaire de phytomania.com<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">COMPOSITION CHIMIQUE ET PROPRIETES<\/h2>\n\n\n\n<p>Les deux plantains d\u00e9crits ont des compositions chimiques voisines, ils contiennent :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>des glycosides d\u2019irido\u00efdes (terp\u00e8nes cycliques li\u00e9s en g\u00e9n\u00e9ral au glucose) pharmacologiquement actifs mais instables (surtout \u00e0 la chaleur), le plus abondant l&rsquo;aucuboside, ces compos\u00e9s ne sont pr\u00e9sents que dans la feuille fraiche,<\/li>\n\n\n\n<li>des flavono\u00efdes communs dans les plantes (apig\u00e9nine, lut\u00e9oline, querc\u00e9tine etc.)et d\u2019autres d\u00e9riv\u00e9s ph\u00e9noliques (acides ph\u00e9nols : acide caf\u00e9ique, chlorog\u00e9nique) et des h\u00e9t\u00e9rosides (de flavonol, d&rsquo;acides ph\u00e9nol),<\/li>\n\n\n\n<li>une substance mucilagineuse (2 \u00e0 6%) riche en arabinose, galactose et acides uroniques (un arabinogalactane anti-inflammatoire),<\/li>\n\n\n\n<li>un peu de vitamine C (8 mg\/100g) et des min\u00e9raux (zinc, silice, potassium),<\/li>\n\n\n\n<li>des glucides (polysaccharides), des tanins(6%), pigments, acides organiques, tr\u00e8s peu de prot\u00e9ines et de lipides, mais sans propri\u00e9t\u00e9s originales,<\/li>\n\n\n\n<li>des alcaloides en tr\u00e8s petite quantit\u00e9 et pharmacologiquement peu actifs.<\/li>\n<\/ul>\n\n\n\n<p>Le MUCILAGE est anti-inflammatoire, aussi bien celui des feuilles que celui des graines (qui sont laxatives douces).<\/p>\n\n\n\n<p>Le JUS DE FEUILLE FRAICHE est :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>vuln\u00e9raire (cicatrisant),<\/li>\n\n\n\n<li>antiseptique (antibact\u00e9rien),<\/li>\n\n\n\n<li>antiprurigineux<\/li>\n\n\n\n<li>et anti-inflammatoire.<\/li>\n<\/ul>\n\n\n\n<p>L\u2019extrait aqueux de feuille (DECOCTION ou INFUSION PROLONGEE) est :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>DIURETIQUE et l\u00e9g\u00e8rement hypotenseur (chez l\u2019animal),<\/li>\n\n\n\n<li>ANTIBIOTIQUE contre des bact\u00e9ries isol\u00e9es de s\u00e9cr\u00e9tions conjonctivales purulentes,<\/li>\n\n\n\n<li>ANTIVIRAL (contre le virus herp\u00e8s),<\/li>\n\n\n\n<li>antispasmodique et ANTI-ALLERGIQUE.<\/li>\n<\/ul>\n\n\n\n<p>Chez l\u2019animal, l\u2019extrait de feuille n\u2019induit pas de choc allergique et semble immunostimulant (stimulation de l\u2019activit\u00e9 phagocytaire des granulocytes).<br>La decoction de feuille et de racine est antioxydant, et pi\u00e9geur de radicaux libres (observations chinoises).<br>La plante ne pr\u00e9sente pas de toxicit\u00e9 aux doses suivantes : d\u00e9coction, 25g\/l par voie buccale et 50g\/l en bain de bouche (1\/4 de litre par jour).<br>La DL50 par voie intraveineuse chez le rat : 175mg\/kg d\u2019extrait aqueux.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"http:\/\/www.imagesud.com\"><img loading=\"lazy\" decoding=\"async\" width=\"336\" height=\"280\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesud2bis.jpg\" alt=\"\" class=\"wp-image-1415\" srcset=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesud2bis.jpg 336w, https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesud2bis-300x250.jpg 300w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><\/a><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><a href=\"http:\/\/www.imagesud.com\">http:\/\/www.imagesud.com<\/a> site partenaire de phytomania.com<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">UTILISATIONS<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">FEUILLES FRAICHES<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les tr\u00e8s JEUNES FEUILLES sont comestibles (pas trop am\u00e8res) en salade ou cuites comme des \u00e9pinards ( vitamines A et C, fer, prot\u00e9ines, mucilage) .<\/li>\n\n\n\n<li>Les plantains sont universellement connus comme PLANTES CICATRISANTES, vuln\u00e9raires.<br>Les feuilles fraiches, nettoy\u00e9es \u00e0 l&rsquo;eau propre sont grossi\u00e8rement froiss\u00e9es ou mieux broy\u00e9es dans un mortier ou dans un mixeur.<br>Les feuilles, froiss\u00e9es, servent de pansement provisoire.<br>Le broyat de feuilles fra\u00eeches peut s&rsquo;appliquer directement sur la peau, pour calmer les d\u00e9mangeaisons et l\u2019irritation des piq\u00fbres d\u2019insectes (moustiques ou abeilles) ou sur des zones contuses et avec plaies.<\/li>\n\n\n\n<li>On peut exposer bri\u00e8vement les feuilles \u00e0 la chaleur, puis les presser, elles donnent alors un \u00abjus \u00bb, COLLYRE efficace pour soigner les conjonctivites et les infections des annexes de l\u2019\u0153il.<br>En cas de n\u00e9cessit\u00e9 la goutte de s\u00e8ve qui perle \u00e0 l&rsquo;extr\u00e9mit\u00e9 d&rsquo;une feuille propre et fraichement coup\u00e9e peut etre instill\u00e9e au coin de l&rsquo;oeil comme un collyre anti-inflammatoire et antibact\u00e9rien.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">INFUSION &#8211; DECOCTION<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Environ une poign\u00e9e de feuilles fraiches ou 2 \u00e0 3 cuiller\u00e9es \u00e0 soupe de feuilles s\u00e8ches dans un litre d&rsquo;eau, \u00e9bullition pendant une minute.<br>L\u2019infusion-d\u00e9coction de feuille est un liquide peu astringent, diur\u00e9tique.<\/li>\n\n\n\n<li>En d\u00e9coction prolong\u00e9e (5 \u00e0 6 minutes), le liquide devient plus astringent mais aussi plus mucilagineux , ses propri\u00e9t\u00e9s anti-inflammatoires, anti\u2013infectieuses et antispasmodiques sont major\u00e9es :<\/li>\n\n\n\n<li>bain d\u2019\u0153il, bain de bouche,<\/li>\n\n\n\n<li>dermatoses suintantes ou prurigineuses, toilette g\u00e9nitale, leucorrh\u00e9e, acn\u00e9 s\u00e9borrh\u00e9ique,<\/li>\n\n\n\n<li>toux spasmodiques, bronchites, laryngites, angines, asthme bronchique.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">TEINTURE ALCOOLIQUE<\/h2>\n\n\n\n<p>On pr\u00e9conise en g\u00e9n\u00e9ral la teinture-m\u00e8re obtenue \u00e0 partir de la plante fraiche, mais la teinture alcoolique obtenue \u00e0 partir des plantes s\u00e8ches est \u00e9galement utile.<\/p>\n\n\n\n<p>-PHARYNGITES, ANGINES : 20 \u00e0 40 gouttes dans un verre d&rsquo;eau ti\u00e8de en gargarisme que l&rsquo;on peut avaler ensuite.<\/p>\n\n\n\n<p>-ASTHME BRONCHIQUE : le plantain est utile en compl\u00e9ment d&rsquo;un traitement personnalis\u00e9 de l&rsquo;asthme, c&rsquo;est une plante mod\u00e9r\u00e9ment antiallergique et antispasmodique et parfaitement tol\u00e9r\u00e9e : 30 \u00e0 60 gouttes par jour en cure de deux mois.<\/p>\n\n\n\n<p>Notons que cette plante utile \u00e0 l&rsquo;asthmatique est par ailleurs allergisante par son pollen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">GRAINES<\/h2>\n\n\n\n<p>Les graines pil\u00e9es et m\u00e9lang\u00e9es \u00e0 un peu d\u2019eau ti\u00e8de sont laxatives par effet mucilagineux (5 \u00e0 20g par jour avec boisson abondante).<br>Les oiseaux les appr\u00e9cient, on peut r\u00e9colter les \u00e9pis en fin de floraison et les faire s\u00e9cher, ils seront utiles en hiver.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">RESUME<\/h2>\n\n\n\n<p>UNE PETITE HERBE COMMUNE POUR CICATRISER<br>Les plantains (le grand et le lanc\u00e9ol\u00e9) sont r\u00e9pandus dans le monde entier,<br>le jus de feuille fra\u00eeche ou la d\u00e9coction sont utiles pour acc\u00e9l\u00e9rer la cicatrisation des plaies<br>m\u00eame un peu infect\u00e9es, calmer les irritations conjonctivales ou les infections de la bouche ,<br>aider \u00e0 calmer l&rsquo;irritation bronchique et les toux spasmodiques; on peut m\u00eame les manger en salade.<br>Copyright 2023 : Dr Jean-Michel Hurtel<\/p>\n\n\n\n<p>Vous \u00eates sur www.phytomania.com<br>site d\u00e9di\u00e9 aux plantes m\u00e9dicinales et aux huiles essentielles<br>PHYTOTHERAPIE, PLANTES MEDICINALES, AROMATHERAPIE, HUILES ESSENTIELLES<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il existe dans le monde plusieurs centaines d&rsquo;esp\u00e8ces de PLANTAINS (PLANTAGINACEAE). PLANTO LANCEOLATA plantain lanc\u00e9ol\u00e9 Les plantains des r\u00e9gions temp\u00e9r\u00e9es sont des plantes vivaces communes et qui sont adaptables au climat tropical ou subtropical on les retrouve donc dans le monde entier sauf les r\u00e9gions tr\u00e8s froides ou trop chaudes. Elles se propagent par leur [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[72,8,45,32,86,37,54,26,110,38,40,142,111,131,135,21,66,98],"tags":[],"class_list":["post-890","post","type-post","status-publish","format-standard","hentry","category-acne-furonculose","category-affections-respiratoires","category-anti-inflammatoire","category-antibiotique","category-antispasmodique","category-antiviral","category-asthme-bronchique","category-astringent-antihemorragique","category-bronchite","category-cicatrisant","category-constipation","category-dermatose","category-diuretique","category-leucorrhee","category-plaies-et-ulceres","category-plante-diuretique","category-vitamine-a","category-vitamine-c","entry"],"_links":{"self":[{"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/posts\/890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/comments?post=890"}],"version-history":[{"count":4,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/posts\/890\/revisions"}],"predecessor-version":[{"id":1576,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/posts\/890\/revisions\/1576"}],"wp:attachment":[{"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/media?parent=890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/categories?post=890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/tags?post=890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}