{"id":92,"date":"2024-05-18T11:53:43","date_gmt":"2024-05-18T09:53:43","guid":{"rendered":"https:\/\/www.phytomania.com\/plantes-medicinales\/?p=92"},"modified":"2025-11-13T11:33:55","modified_gmt":"2025-11-13T10:33:55","slug":"andrographis","status":"publish","type":"post","link":"https:\/\/www.phytomania.com\/plantes-medicinales\/andrographis\/","title":{"rendered":"ANDROGRAPHIS"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.phytomania.com\/herbal-medicine\/andrographis\/\"><img loading=\"lazy\" decoding=\"async\" width=\"32\" height=\"32\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/05\/EnglishLanguage_Flag1_26107.png\" alt=\"\" class=\"wp-image-44\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.phytomania.com\/medicina-herbaria\/andrographis\/\"><img loading=\"lazy\" decoding=\"async\" width=\"32\" height=\"32\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/05\/Spain_flags_flag_8858.png\" alt=\"\" class=\"wp-image-42\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"165\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/05\/bacopa-monnieri-1.jpg\" alt=\"\" class=\"wp-image-246\"\/><\/figure>\n\n\n\n<p>Andrographis paniculata (= Justicia paniculata) est une acanthaceae, originaire de la r\u00e9gion indo-malaise, o\u00f9 elle est consid\u00e9r\u00e9e comme une plante m\u00e9dicinale de premi\u00e8re importance. C&rsquo;est le KING OF BITTERS dans les pays de langue anglaise.<\/p>\n\n\n\n<p>Les acanthaceae sont assez rares dans les r\u00e9gions temp\u00e9r\u00e9es et plus fr\u00e9quentes dans les r\u00e9gions chaudes, on en d\u00e9crit plusieurs milliers d&rsquo;esp\u00e8ces.<\/p>\n\n\n\n<p>En Europe on connait l&rsquo;acanthe (Acanthus mollis) aux feuilles grandes et d\u00e9coup\u00e9es, souvent repr\u00e9sent\u00e9es dans les sculptures antiques et qui est pr\u00e9sente comme plante vivace d\u00e9corative (pour ses fleurs blanches et son feuillage) dans de nombreux jardins du sud de la France.<\/p>\n\n\n\n<p>Les acanthaceae tropicales d\u00e9coratives par les fleurs et leur feuillage sont surtout des Thunbergia ou des Justicia.<\/p>\n\n\n\n<p>Andrographis paniculata poss\u00e8de des tiges quadrangulaires l\u00e9g\u00e8rement ail\u00e9es et rainur\u00e9es avec des feuilles lanc\u00e9ol\u00e9es de 5 \u00e0 8 cm de long et 2 \u00e0 3 cm de large, les fleurs en rac\u00e8me tr\u00e8s l\u00e2che poss\u00e8dent des p\u00e9tales tach\u00e9s de pourpre violac\u00e9, les fruits sont des capsules d&rsquo;environ 1 \u00e0 3 cm de long contenant de petites graines jaunes ou marron.<\/p>\n\n\n\n<p>Andrographis paniculata, \u00ab\u00a0king of bitters\u00a0\u00bb en anglais (le roi des amers), poss\u00e8de de nombreux noms locaux dans toutes les langues Asiatiques.<br>Les tiges et les feuilles sont les parties m\u00e9dicinales.<\/p>\n\n\n\n<p>ANDROGRAPHIS PANICULATA KING OF BITTERS PLANTE AMERE GRIPPE FIEVRE RHUME HEPATITE INFECTIONS ANTI-INFLAMMATOIRE DEFENSE IMMUNITAIRE BRONCHITE COLITE<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"http:\/\/www.imagesud.com\"><img loading=\"lazy\" decoding=\"async\" width=\"336\" height=\"280\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesudbis.jpg\" alt=\"\" class=\"wp-image-1418\" srcset=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesudbis.jpg 336w, https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesudbis-300x250.jpg 300w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><\/a><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><a href=\"http:\/\/www.imagesud.com\">http:\/\/www.imagesud.com<\/a> site partenaire de phytomania.com<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">COMPOSITION CHIMIQUE ET PROPRIETES<\/h2>\n\n\n\n<p>Andrographis paniculata est une plante m\u00e9dicinale traditionnelle de la r\u00e9gion indo-malaise, connue depuis longtemps par les m\u00e9decins ayurv\u00e9diques , et par les m\u00e9decins Anglais depuis leur \u00ab\u00a0conqu\u00eate\u00a0\u00bb de l&rsquo;Inde.<br>En Asie elle fait l&rsquo;objet de recherches pharmacologiques et cliniques depuis quelques dizaines d&rsquo;ann\u00e9es.<br><br>LES ANDROGRAPHOLIDES : PRINCIPAUX COMPOSANTS D&rsquo;ANDROGRAPHIS PANICULATA<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"190\" height=\"188\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2024\/05\/bacopa-monnieri-fleur-1.jpg\" alt=\"\" class=\"wp-image-247\"\/><\/figure>\n\n\n\n<p>Andrographis paniculata est une plante particuli\u00e8rement am\u00e8re, cette amertume est li\u00e9e \u00e0 la pr\u00e9sence de lactones diterp\u00e9niques (substance chimique construite par la plante \u00e0 partir de 4 unit\u00e9s isopr\u00e8nes et poss\u00e8dant un cycle interne assur\u00e9 par de l&rsquo;oxyg\u00e8ne).<\/p>\n\n\n\n<p>Ces substances am\u00e8res sont caract\u00e9ristiques de la plante : l&rsquo;ANDROGRAPHOLIDE et des mol\u00e9cules tr\u00e8s proches ( exemples: d\u00e9oxyandrographolide, n\u00e9oandrographolide)<br>Ces mol\u00e9cules ont \u00e9t\u00e9 r\u00e9cemment \u00e9tudi\u00e9es surtout en Asie elles sont :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>ANTI-INFLAMMATOIRES et tr\u00e8s efficaces pour pi\u00e9ger les radicaux libres.<br>Nombre de leurs propri\u00e9t\u00e9 pharmacologiques sont relatives \u00e0 cette capacit\u00e9 \u00e0 neutraliser les radicaux chimiques tr\u00e8s r\u00e9actifs qui d\u00e9t\u00e9riorent ou d\u00e9truisent les cellules.<\/li>\n\n\n\n<li>ANTI-MICROBIENNES ET ANTI-VIRALES, utiles pour combattre les infections respiratoires de type grippales, les bronchites.<\/li>\n\n\n\n<li>Utiles CONTRE LA DIARRHEE AIGUE(collibacillose), certains th\u00e9rapeutes l&rsquo;ont essayer pour att\u00e9nuer les symptomes de colite ulc\u00e9reuse (trouble chronique du colon et du rectum).<\/li>\n\n\n\n<li>RENFORCEMENT DE LA DEFENSE IMMUNITAIRE . Le pouvoir anti-infectieux d&rsquo;Andrographis paniculata est sans doute plut\u00f4t la cons\u00e9quence d&rsquo;une augmentation des d\u00e9fenses de l&rsquo;organisme que d&rsquo;une action sur les agents de l&rsquo;infection.<\/li>\n\n\n\n<li>ANTI-DIABETIQUE (de type 2) , \u00e9tudes principalement effectu\u00e9es sur l&rsquo;animal.<\/li>\n\n\n\n<li>PREVENTION DE LA DEGENERESCENCE CANCEREUSE ou ralentissement du d\u00e9veloppement du cancer(peut-\u00eatre par un effet anti-angiog\u00e9nique) : notamment cancer de la prostate, cancer du colon, et cancer broncho-pulmonaire.<\/li>\n\n\n\n<li>PROTECTION DES CELLULES DU FOIE: en cas d&rsquo;agression chimique ou virale, h\u00e9patite, cirrhose.<\/li>\n\n\n\n<li>L&rsquo;andrographolide et certains compos\u00e9s tr\u00e8s proches (Dehydroandrographolide) sont \u00e9tudi\u00e9s et exp\u00e9riment\u00e9s en Chine pour lutter contre certains cancers difficiles \u00e0 soigner comme les gliomes (cancer du cerveau).<\/li>\n<\/ul>\n\n\n\n<p>FLAVONOIDES ET POLYPHENOLS D&rsquo;ANDROGRAPHIS PANICULATA<\/p>\n\n\n\n<p>Ces compos\u00e9s communs dans les plantes sont \u00e9galement de bon pi\u00e9geurs de radicaux libres et donc prot\u00e8gent les tissus.<\/p>\n\n\n\n<p>Dans le cas d&rsquo;Andrographis paniculata, en association avec les \u00ab\u00a0andrographolides\u00a0\u00bb ils sont int\u00e9ressants :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>pour controler les troubles des lipides sanguins : hyper-cholest\u00e9rol\u00e9mie, dyslipid\u00e9mie, d\u00e9s\u00e9quilibre entre cholest\u00e9rol li\u00e9 aux HDL et LDL,<\/li>\n\n\n\n<li>et pour diminuer l&rsquo;intol\u00e9rance tissulaire \u00e0 l&rsquo;insuline responsable de l&rsquo;aggravation du diab\u00e8te de type 2 (effet antidiab\u00e9tique)<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"http:\/\/www.imagesud.com\"><img loading=\"lazy\" decoding=\"async\" width=\"336\" height=\"280\" src=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesud2bis.jpg\" alt=\"\" class=\"wp-image-1415\" srcset=\"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesud2bis.jpg 336w, https:\/\/www.phytomania.com\/plantes-medicinales\/wp-content\/uploads\/2025\/06\/imagesud2bis-300x250.jpg 300w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><\/a><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><a href=\"http:\/\/www.imagesud.com\">http:\/\/www.imagesud.com<\/a> site partenaire de phytomania.com<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">UTILISATIONS<\/h2>\n\n\n\n<p>PREVENTION ET TRAITEMENT DES INFECTIONS VIRALES ET BACTERIENNES<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Infections \u00ab\u00a0grippales\u00a0\u00bb ou plus g\u00e9n\u00e9ralement \u00e0 virus des voies respiratoires (rhume commun), angines virales, bronchites, mais \u00e9galement les arboviroses tropicales (dengue, chikungunya).<\/li>\n\n\n\n<li>Infections du bas de l&rsquo;appareil urinaire (cystite, ur\u00e9thrite),<\/li>\n\n\n\n<li>Infections intestinales : diarrh\u00e9e \u00e0 collibacile et colite, dysenterie (en Asie).<\/li>\n<\/ul>\n\n\n\n<p>EXEMPLES DE POSOLOGIE:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Plante s\u00e8che : en g\u00e9n\u00e9ral 1 \u00e0 3 g de poudre d&rsquo; Andrographis paniculata 3 fois par jour, mais 9 g de poudre de plante s\u00e8che en une prise deux fois par jour en cas d&rsquo;infection intestinale aigue (en absence d&rsquo;antibiotique).<\/li>\n\n\n\n<li>Extrait standardis\u00e9 en andrographolide, le pourcentage en est variable selon les pr\u00e9parations (de 4 \u00e0 6% et jusqu&rsquo;\u00e0 45%).<br>Les doses journali\u00e8res sont variables en fonction du pourcentage de produit actif.<br>Exemple : 400mg d&rsquo;extrait \u00e0 4 ou 6% 3 fois par jour pour un rhume banal , et deux fois cette dose pour une infection plus s\u00e9rieuse.<br>Pour un extrait \u00e0 30 \u00e0 40% d&rsquo;andrographolide , 150 \u00e0 200mg par jour.<\/li>\n\n\n\n<li>La d\u00e9coction d&rsquo;andrographis est parfois pr\u00e9conis\u00e9e en Asie mais \u00e9tant donn\u00e9 la forte amertume de cette plante, je la d\u00e9conseille, au m\u00eame titre que la teinture alcoolique ou la teinture-m\u00e8re.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">RENFORCEMENT DE LA DEFENSE IMMUNITAIRE (INFECTIONS, CANCERS)<\/h2>\n\n\n\n<p>Cure de 2 \u00e0 3 semaines tous les 2 mois ou au d\u00e9but de l&rsquo;hiver \u00e0 raison de 1 \u00e0 2g de poudre d&rsquo;andrographis paniculata par jour ou 400 mg d&rsquo;extrait \u00e0 4-6% 1 \u00e0 2 fois par jour.<\/p>\n\n\n\n<p>DIABETE mod\u00e9r\u00e9 de type 2, HEPATITE virale ou d\u00e9but de processus cirrhotique<\/p>\n\n\n\n<p>M\u00eame posologie que pour le renforcement de l&rsquo;immunit\u00e9<br>AUTRES UTILISATIONS<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>MORSURES DE SERPENTS : En Inde et dans la r\u00e9gion indo-malaise, on utilise les extraits d&rsquo;andrographis paniculata en cas de morsure de serpent souvent en association avec un s\u00e9rum antivenimeux polyvalent.<\/li>\n\n\n\n<li>PALUDISME : Son amertume (qui rappelle celle de la quinine ou du neem) est peut-\u00eatre \u00e0 l&rsquo;origine de son utilisation comme antipalud\u00e9en (quelques \u00e9tudes confortent cette possibilit\u00e9).<\/li>\n\n\n\n<li>DENGUE ET CHIKUNGUNYA : R\u00e9cemment des \u00e9pid\u00e9mies importante de dengue et de chikungunya se sont d\u00e9velopp\u00e9es dans la r\u00e9gion indo malaise, devant l&rsquo;absence de traitements ou de vaccins, les malades et les m\u00e9decins ont essay\u00e9 des traitements alternatifs, certains avec succ\u00e8s, en particulier avec les extraits de feuille de papayer mais aussi d&rsquo;Andrographis paniculata.<\/li>\n\n\n\n<li>MEDECINE AYURVEDIQUE : C&rsquo;est une plante m\u00e9dicinale importante dans la m\u00e9decine ayurv\u00e9dique.<\/li>\n\n\n\n<li>NOURRITURE ANIMALE : Une \u00e9tude malaise sur les effets, chez la ch\u00e8vre \u00e9lev\u00e9e pour la viande, d&rsquo;un compl\u00e9ment alimentaire de poudre d&rsquo;andrographis \u00e0 1,5% de la ration alimentaire montre que la viande est de meilleur qualit\u00e9, que l&rsquo;animal est plus lourd et que le rapport viande\/graisse est am\u00e9lior\u00e9. On attribue ces effets \u00e0 une meilleure digestion des v\u00e9g\u00e9taux, un effet semblable \u00e0 celui obtenu avec des antibiotiques mais sans les inconv\u00e9nients de ces derniers.<br>PRECAUTIONS<\/li>\n<\/ul>\n\n\n\n<p>Certaines (rares) personnes sont allergiques \u00e0 Andrographis paniculata ou \u00e0 ces extraits. Ce sont en g\u00e9n\u00e9ral des personnes multi-allergiques au terrain atopique, et qui sont prudentes quand il s&rsquo;agit d&rsquo;exp\u00e9rimenter de nouveau traitement.<br>Il est pr\u00e9f\u00e9rable d&rsquo;\u00e9viter de consommer cette plante ou ses extraits quand on est enceinte ou qu&rsquo;on allaite, et chez le jeune enfant ( en dessous de 6 ans).<br>OU TROUVER ANDROGRAPHIS PANICULATA ?<\/p>\n\n\n\n<p>Andrographis paniculata est une plante qui peut \u00eatre commune dans les pays chauds o\u00f9 il a \u00e9t\u00e9 introduit, et dans lesquels il est assez facile de ce procurer la plante fraiche ou s\u00e8che.<br>En Asie on peut trouver assez facilement des extraits en pharmacie ou dans les herboristeries, ailleurs et grace \u00e0 internet on peut se procurer des extraits y compris en Europe (exemple su\u00e8de avec le Swedish Herbal Institutes qui commercialise un m\u00e9lange pour renforcer l&rsquo;immunit\u00e9 : andrographis, \u00e9leutherocoque et sureau).<br>La tisane ou la d\u00e9coction de parties a\u00e9riennes d&rsquo;Andrographis paniculata est difficlie \u00e0 proposer \u00e0 cause de la grande amertume de la plante (mais certaines personnes supportent tr\u00e8s bien l&rsquo;amer), il est donc pr\u00e9f\u00e9rable d&rsquo;utiliser la poudre de plante s\u00e8che en comprim\u00e9s enrob\u00e9s ou en g\u00e9lules (bien \u00e9tanches).<br>Les extraits d&rsquo;Andrographis paniculata titr\u00e9s en andrographolides sont les plus commodes \u00e0 employer.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">CULTURE D&rsquo;ANDROGRAPHIS PANICULATA, \u00ab\u00a0KING OF BITTERS\u00a0\u00bb<\/h2>\n\n\n\n<p>C&rsquo;est une plante tr\u00e8s facile \u00e0 cultiver dans les pays chauds comme plante annuelle, elle s&rsquo;accommode de presque tous les terrains (y compris les terrains secs avec irrigation), elle est tr\u00e8s peu sensible aux parasites et n&rsquo;est pas brout\u00e9e par les herbivores (saufs les ch\u00e8vres affam\u00e9es!!).<\/p>\n\n\n\n<p>On peut la cultiver en pleine terre ou en pots et containers.<\/p>\n\n\n\n<p>C&rsquo;est une plante m\u00e9dicinale importante qui a \u00e9t\u00e9 introduite dans de nombreux pays tropicaux parfois par inadvertance parfois comme plante d\u00e9corative mais \u00e0 laquelle on devrait s&rsquo;int\u00e9resser beaucoup plus, elle soigne des maladies tr\u00e8s communes, renforce les d\u00e9fenses de l&rsquo;organisme et ne pr\u00e9sente pas de toxicit\u00e9 aux doses indiqu\u00e9es dans cette page.<\/p>\n\n\n\n<p>La propagation se fait par les graines avec repiquage des jeunes plantules, on recueille les feuilles avant la floraison.<\/p>\n\n\n\n<p>On exp\u00e9rimente actuellement en Inde des techniques de culture qui permettent une concentration sup\u00e9rieure en andrographolides en faisant supporter \u00e0 la plante un stress osmotique : culture sur des terrains l\u00e9g\u00e8rement sal\u00e9s, ou irrigation avec des eaux salines.<\/p>\n\n\n\n<p>PLANTES MEDICINALES COUSINES D&rsquo;ANDROGRAPHIS PANICULATA<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Justicia pectoralis, qui fait partie de la pharmacop\u00e9e Fran\u00e7aise, plus connue aux antilles comme \u00ab\u00a0herbe charpentier\u00a0\u00bb, utile pour soigner les plaies, faciliter la cicatrisation, mais aussi pour calmer, apaiser.<\/li>\n\n\n\n<li>Justicia gendarussa, plante asiatique, surtout utilis\u00e9e dans la r\u00e9gion indon\u00e9sienne, qui poss\u00e8de un effet contraceptif masculin par inhibition d&rsquo;un enzyme du spermatozoide lui permettant de p\u00e9n\u00e9trer dans l&rsquo;ovule, emp\u00eachant de ce fait la f\u00e9condation mais sans intervenir sur la sexualit\u00e9 masculine.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">RESUME<\/h2>\n\n\n\n<p>UNE PLANTE MEDICINALE D&rsquo;ASIE CONTRE LES INFECTIONS ET POUR RENFORCER L&rsquo;IMMUNITE<br>Andrographis paniculata est originaire d&rsquo;Asie, elle renforce l&rsquo;immunit\u00e9 et les d\u00e9fenses de l&rsquo;organisme, permet d&rsquo;att\u00e9nuer les effets des infections virales comme le rhume, la grippe mais aussi la dengue . Elle poss\u00e8de un effet antidiab\u00e9tique et r\u00e9gule les lipides sanguins. Des recherches r\u00e9centes ont d\u00e9couvert chez elle des mol\u00e9cules anti-canc\u00e9reuses. C&rsquo;est une plante tr\u00e8s am\u00e8re, utilis\u00e9e depuis longtemps par les tradipraticiens asiatiques. Elle se cultive facilement dans tous les pays chauds.<\/p>\n\n\n\n<p>Copyright 2023 : Dr Jean-Michel Hurtel<\/p>\n\n\n\n<p>Vous \u00eates sur www.phytomania.com<br>site d\u00e9di\u00e9 aux plantes m\u00e9dicinales et aux huiles essentielles<br>PHYTOTHERAPIE, PLANTES MEDICINALES, AROMATHERAPIE, HUILES ESSENTIELLES<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Andrographis paniculata (= Justicia paniculata) est une acanthaceae, originaire de la r\u00e9gion indo-malaise, o\u00f9 elle est consid\u00e9r\u00e9e comme une plante m\u00e9dicinale de premi\u00e8re importance. C&rsquo;est le KING OF BITTERS dans les pays de langue anglaise. Les acanthaceae sont assez rares dans les r\u00e9gions temp\u00e9r\u00e9es et plus fr\u00e9quentes dans les r\u00e9gions chaudes, on en d\u00e9crit plusieurs [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,45,37,6,24,30,33,2,7,34],"tags":[],"class_list":["post-92","post","type-post","status-publish","format-standard","hentry","category-affections-respiratoires","category-anti-inflammatoire","category-antiviral","category-cancer","category-diabete","category-episode-febrile","category-immunostimulant","category-plante-medicinale","category-troubles-digestifs","category-troubles-du-cholesterol","entry"],"_links":{"self":[{"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/posts\/92","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/comments?post=92"}],"version-history":[{"count":7,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/posts\/92\/revisions"}],"predecessor-version":[{"id":1788,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/posts\/92\/revisions\/1788"}],"wp:attachment":[{"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/media?parent=92"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/categories?post=92"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.phytomania.com\/plantes-medicinales\/wp-json\/wp\/v2\/tags?post=92"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}